{"id":108328,"date":"2026-03-19T11:46:41","date_gmt":"2026-03-19T14:46:41","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=108328"},"modified":"2026-03-19T11:46:42","modified_gmt":"2026-03-19T14:46:42","slug":"lo-engancho-la-policia-en-la-caldera-cuando-habia-terminado-de-faenar-una-vaca-robada","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2026\/03\/19\/lo-engancho-la-policia-en-la-caldera-cuando-habia-terminado-de-faenar-una-vaca-robada\/","title":{"rendered":"Lo enganch\u00f3 la Polic\u00eda en la Caldera cuando hab\u00eda terminado de faenar una vaca robada"},"content":{"rendered":"\n<p>La Polic\u00eda Rural y Ambiental logr\u00f3 ubicar al acusado en una finca ubicada en La Caldera luego de recibir la denuncia de una mujer por la sustracci\u00f3n de una vaca.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"705\" src=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/03\/image-163-1024x705.png\" alt=\"\" class=\"wp-image-108330\" srcset=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/03\/image-163-1024x705.png 1024w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/03\/image-163-300x206.png 300w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/03\/image-163-768x529.png 768w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/03\/image-163-610x420.png 610w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/03\/image-163-218x150.png 218w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/03\/image-163-696x479.png 696w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/03\/image-163-1068x735.png 1068w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/03\/image-163-100x70.png 100w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/03\/image-163.png 1222w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>El procedimiento fue esta madrugada en una finca ubicada sobre ruta nacional 9, en La Caldera, donde fue reportado al Sistema de Emergencias 911 un caso de faena clandestina.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"490\" height=\"651\" src=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/03\/image-164.png\" alt=\"\" class=\"wp-image-108331\" style=\"width:1056px;height:auto\" srcset=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/03\/image-164.png 490w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/03\/image-164-226x300.png 226w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/03\/image-164-316x420.png 316w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/03\/image-164-300x399.png 300w\" sizes=\"auto, (max-width: 490px) 100vw, 490px\" \/><\/figure>\n\n\n\n<p>En el lugar incautaron m\u00e1s de 150 kilos de carne y detuvieron a un hombre de 54 a\u00f1os que fue denunciado por una mujer por haber faenado animales de su propiedad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Polic\u00eda Rural y Ambiental logr\u00f3 ubicar al acusado en una finca ubicada en La Caldera luego de recibir la denuncia de una mujer por la sustracci\u00f3n de una vaca. El procedimiento fue esta madrugada en una finca ubicada sobre ruta nacional 9, en La Caldera, donde fue reportado al Sistema de Emergencias 911 un [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":108329,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[73],"tags":[],"class_list":{"0":"post-108328","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-general"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/108328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=108328"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/108328\/revisions"}],"predecessor-version":[{"id":108332,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/108328\/revisions\/108332"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/108329"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=108328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=108328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=108328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}