{"id":108389,"date":"2026-03-20T14:08:04","date_gmt":"2026-03-20T17:08:04","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=108389"},"modified":"2026-03-20T14:09:24","modified_gmt":"2026-03-20T17:09:24","slug":"detienen-a-2-delincuentes-que-robaron-143-choclos-en-una-finca-de-r-de-lerma","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2026\/03\/20\/detienen-a-2-delincuentes-que-robaron-143-choclos-en-una-finca-de-r-de-lerma\/","title":{"rendered":"Detienen a 2 delincuentes que robaron 143 choclos en una finca de R\u00b0 de Lerma"},"content":{"rendered":"\n<p>La denuncia fue realizada por el propietario de una propiedad rural, quien advirti\u00f3 la sustracci\u00f3n reiterada de choclos y da\u00f1os causados en las plantaciones. Los sospechosos fueron aprehendidos en inmediaciones del lugar con parte de lo sustra\u00eddo.<\/p>\n\n\n\n<p>El fiscal penal de Rosario de Lerma, Daniel Alejandro Escalante, imput\u00f3 provisionalmente a dos hombres de 30 y 33 a\u00f1os, como coautores de los delitos de hurto simple y da\u00f1os en concurso real.<\/p>\n\n\n\n<p>El hecho investigado ocurri\u00f3 el pasado 13 de marzo en una finca ubicada en la zona de Ruta Provincial 23, donde los imputados habr\u00edan ingresado sin autorizaci\u00f3n y sustra\u00eddo un total de 143 choclos, propiedad del denunciante.<\/p>\n\n\n\n<p>De acuerdo a la investigaci\u00f3n, empleados del lugar advirtieron la presencia de personas en la plantaci\u00f3n, y posteriormente personal policial logr\u00f3 interceptar a los acusados en las inmediaciones, cuando transportaban bolsas con los elementos sustra\u00eddos, los cuales fueron secuestrados.<\/p>\n\n\n\n<p>Asimismo, se constat\u00f3 mediante inspecci\u00f3n ocular y registros fotogr\u00e1ficos la existencia de da\u00f1os en las plantaciones, lo que gener\u00f3 un perjuicio econ\u00f3mico al propietario.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La denuncia fue realizada por el propietario de una propiedad rural, quien advirti\u00f3 la sustracci\u00f3n reiterada de choclos y da\u00f1os causados en las plantaciones. Los sospechosos fueron aprehendidos en inmediaciones del lugar con parte de lo sustra\u00eddo. El fiscal penal de Rosario de Lerma, Daniel Alejandro Escalante, imput\u00f3 provisionalmente a dos hombres de 30 y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":108391,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[73],"tags":[],"class_list":{"0":"post-108389","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-general"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/108389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=108389"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/108389\/revisions"}],"predecessor-version":[{"id":108390,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/108389\/revisions\/108390"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/108391"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=108389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=108389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=108389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}