{"id":108651,"date":"2026-03-28T12:20:58","date_gmt":"2026-03-28T15:20:58","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=108651"},"modified":"2026-03-28T12:20:59","modified_gmt":"2026-03-28T15:20:59","slug":"impactante-accidente-en-tigre-una-moto-cruzo-en-rojo-choco-con-un-auto-y-sus-ocupantes-salieron-volando","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2026\/03\/28\/impactante-accidente-en-tigre-una-moto-cruzo-en-rojo-choco-con-un-auto-y-sus-ocupantes-salieron-volando\/","title":{"rendered":"Impactante accidente en Tigre: una moto cruz\u00f3 en rojo, choc\u00f3 con un auto y sus ocupantes salieron volando"},"content":{"rendered":"\n<p>El incidente ocurri\u00f3 durante la madrugada en General Pacheco. Las v\u00edctimas fueron trasladadas al hospital y est\u00e1n fuera de peligro.<\/p>\n\n\n\n<p>Un impactante accidente en Tigre no termin\u00f3 en tragedia de milagro. Dos personas que circulaban en una moto volaron por el aire tras chocar de frente contra un auto y salvaron su vida de casualidad.<\/p>\n\n\n\n<p>Toda la secuencia qued\u00f3 registrada por las c\u00e1maras de seguridad del municipio. El hecho ocurri\u00f3 durante la madrugada en la intersecci\u00f3n de la Avenida de los Constituyentes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/03\/image-222-1024x576.png\" alt=\"\" class=\"wp-image-108653\" srcset=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/03\/image-222-1024x576.png 1024w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/03\/image-222-300x169.png 300w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/03\/image-222-768x432.png 768w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/03\/image-222-1536x864.png 1536w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/03\/image-222-747x420.png 747w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/03\/image-222-696x392.png 696w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/03\/image-222-1068x601.png 1068w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/03\/image-222.png 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Seg\u00fan se puede observar en las im\u00e1genes captadas por el Centro de Operaciones Tigre (COT), el conductor de la moto cometi\u00f3 una grave imprudencia: cruz\u00f3 el sem\u00e1foro en rojo e impact\u00f3 de frente con un autom\u00f3vil que circulaba correctamente en sentido contrario.<\/p>\n\n\n\n<p>La violencia del choque hizo que tanto el conductor de la moto como su acompa\u00f1ante salieran despedidos, cayendo pesadamente sobre el asfalto.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Impactante choque en General Pacheco: moto cruz\u00f3 en rojo y sus ocupantes salieron despedidos\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/wk5v2TS0l0w?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Inmediatamente, los operadores de las c\u00e1maras de monitoreo, que vieron el choque en tiempo real, activaron el protocolo de emergencia y dieron aviso a los m\u00f3viles policiales y de salud m\u00e1s cercanos.<\/p>\n\n\n\n<p>A los pocos minutos, personal de Defensa Civil y m\u00e9dicos del Sistema de Emergencias Tigre (SET) arribaron al lugar para asistir a los heridos.<\/p>\n\n\n\n<p>A pesar de la espectacularidad del impacto y de la ca\u00edda, ambos fueron trasladados al Hospital General Pacheco \u201cMagdalena V. de Mart\u00ednez\u201d, donde se confirm\u00f3 que se encuentran fuera de peligro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El incidente ocurri\u00f3 durante la madrugada en General Pacheco. Las v\u00edctimas fueron trasladadas al hospital y est\u00e1n fuera de peligro. Un impactante accidente en Tigre no termin\u00f3 en tragedia de milagro. Dos personas que circulaban en una moto volaron por el aire tras chocar de frente contra un auto y salvaron su vida de casualidad. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":108652,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[73],"tags":[],"class_list":{"0":"post-108651","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-general"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/108651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=108651"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/108651\/revisions"}],"predecessor-version":[{"id":108654,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/108651\/revisions\/108654"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/108652"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=108651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=108651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=108651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}