{"id":109796,"date":"2026-05-05T13:22:06","date_gmt":"2026-05-05T16:22:06","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=109796"},"modified":"2026-05-05T13:22:07","modified_gmt":"2026-05-05T16:22:07","slug":"piqueteros-y-organizaciones-sociales-marchan-desde-tartagal-a-salta-para-reunirse-con-saenz","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2026\/05\/05\/piqueteros-y-organizaciones-sociales-marchan-desde-tartagal-a-salta-para-reunirse-con-saenz\/","title":{"rendered":"Piqueteros y organizaciones sociales marchan desde Tartagal a Salta para reunirse con S\u00e1enz"},"content":{"rendered":"\n<p>Un grupo de aproximadamente 100 personas parti\u00f3 desde Tartagal con destino a la ciudad de Salta, en el marco de una movilizaci\u00f3n que busca ser escuchada por el gobernador Gustavo S\u00e1enz.<\/p>\n\n\n\n<p>Los manifestantes tienen como objetivo entregar en mano un petitorio, planteando sus reclamos y necesidades directamente al mandatario provincial.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"371\" src=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-19-1024x371.png\" alt=\"\" class=\"wp-image-109797\" srcset=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-19-1024x371.png 1024w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-19-300x109.png 300w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-19-768x278.png 768w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-19-1158x420.png 1158w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-19-696x252.png 696w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-19-1068x387.png 1068w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-19.png 1230w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Durante el recorrido, en General Enrique Mosconi se sum\u00f3 otro grupo de personas que aguardaba la llegada de la columna principal. Con esta incorporaci\u00f3n, se estima que la marcha alcanzar\u00e1 cerca de 300 participantes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"1024\" src=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-20-750x1024.png\" alt=\"\" class=\"wp-image-109798\" style=\"width:1068px;height:auto\" srcset=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-20-750x1024.png 750w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-20-220x300.png 220w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-20-768x1048.png 768w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-20-308x420.png 308w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-20-300x409.png 300w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-20-696x950.png 696w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-20.png 861w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p>La movilizaci\u00f3n contin\u00faa avanzando y no se descarta que se sigan sumando m\u00e1s personas a lo largo del trayecto.<\/p>\n\n\n\n<p>El motivo es un pedido al Gobierno de la Provincia de Salta por mejores condiciones en el acceso a Salud P\u00fablica, Educaci\u00f3n, agua y trabajo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un grupo de aproximadamente 100 personas parti\u00f3 desde Tartagal con destino a la ciudad de Salta, en el marco de una movilizaci\u00f3n que busca ser escuchada por el gobernador Gustavo S\u00e1enz. Los manifestantes tienen como objetivo entregar en mano un petitorio, planteando sus reclamos y necesidades directamente al mandatario provincial. Durante el recorrido, en General [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":109799,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[73],"tags":[],"class_list":{"0":"post-109796","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-general"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/109796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=109796"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/109796\/revisions"}],"predecessor-version":[{"id":109800,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/109796\/revisions\/109800"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/109799"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=109796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=109796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=109796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}