{"id":109842,"date":"2026-05-06T13:12:20","date_gmt":"2026-05-06T16:12:20","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=109842"},"modified":"2026-05-06T13:18:05","modified_gmt":"2026-05-06T16:18:05","slug":"saenz-en-5-lugar-en-el-ranking-de-gobernadores-con-imagen-positiva-1-figueroa-de-neuquen-y-ultimo-kicillof","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2026\/05\/06\/saenz-en-5-lugar-en-el-ranking-de-gobernadores-con-imagen-positiva-1-figueroa-de-neuquen-y-ultimo-kicillof\/","title":{"rendered":"S\u00e1enz en 5\u00b0 lugar en el ranking de gobernadores con imagen positiva: 1\u00b0 Figueroa de Neuqu\u00e9n y ultimo Kicillof"},"content":{"rendered":"\n<p>El gobernador de Neuqu\u00e9n, Rolando Figueroa, es el mandatario provincial mejor valorado por la ciudadan\u00eda, con un 56,1% de imagen positiva y -40,7% de imagen negativa, y un diferencial favorable de 54,0%, seg\u00fan una encuesta conocida este mi\u00e9rcoles.<\/p>\n\n\n\n<p>El muestreo realizado a nivel pa\u00eds por la consultora CB Global Data y al que tuvo acceso la Agencia Noticias Argentinas, posiciona a Figueroa como el gobernador m\u00e1s valorado, seguido por sus hom\u00f3logos de San Luis, Claudio Poggi, con un 55,7 de positiva y -41,6 de negativa, y de Tucum\u00e1n, Osvaldo Jaldo con 55,1 y -41,0.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"719\" height=\"399\" src=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-30.png\" alt=\"\" class=\"wp-image-109844\" style=\"width:1059px;height:auto\" srcset=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-30.png 719w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-30-300x166.png 300w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-30-696x385.png 696w\" sizes=\"auto, (max-width: 719px) 100vw, 719px\" \/><\/figure>\n\n\n\n<p><strong>El gobernador de Neuqu\u00e9n,\u00a0Rolando Figueroa<\/strong><\/p>\n\n\n\n<p>El sondeo abarc\u00f3 24.574 casos en las 23 provincias y la Capital Federal, con un promedio de 882 casos por provincia y un margen de error de entre 2,9 y 3,3 por ciento, y fue realizado entre el 1 y el 4 de mayo, con un sistema on line en el que cada mandatario fue evaluado por sus comprovincianos.<\/p>\n\n\n\n<p>En el caso de Figueroa los neuquinos lo evaluaron con una imagen \u201cMuy buena\u201d en un 31,8% y \u201cBuena\u201d en un 24,3%; mientras que un -27,3 eligi\u00f3 la opci\u00f3n \u201cMala\u201d y un -13,4 vot\u00f3 \u201cMala\u201d, lo que lo dej\u00f3 con un diferencial favorable de 54,0%.<\/p>\n\n\n\n<p>EL segundo en el ranking, el puntano Poggi, obtuvo un 29,9 de \u201cMuy buena\u201d, un 25,8 de \u201cBuena\u201d, un -20,6 de \u201cMala\u201d y un -21,0 \u201cMuy mala\u201d, con una diferencia positiva de 55,3%<\/p>\n\n\n\n<p>El tercero en la n\u00f3mina, el tucumano Jaldo, logr\u00f3 un 27,2% de \u201cMuy buena\u201d, un 32,9% de \u201cBuena\u201d, un -28,6% de \u201cMuy mala\u201d y un -12,4% de \u201cMala\u201d, con un diferencial favorable de 54,9%.<\/p>\n\n\n\n<p>En el otro extremo del ranking, los gobernadores peor calificados de mayo de 2026 son Alberto Weretilneck de R\u00edo Negro, quien se ubica en el \u00faltimo lugar con un 41,8% de imagen positiva; seguido por Ricardo Quintela de La Rioja, ante\u00faltimo con 42,5%; y el bonaerense Axel Kicillof con 43,1% de aprobaci\u00f3n.<\/p>\n\n\n\n<p>En cuanto a las variaciones respecto de la medici\u00f3n anterior, el gobernador que registr\u00f3 el mayor crecimiento en su imagen positiva fue Gustavo Melella de Tierra del Fuego, con una suba de +2,3 puntos porcentuales.<\/p>\n\n\n\n<p>Por contrapartida, la mayor ca\u00edda del mes correspondi\u00f3 a Leandro Zdero de Chaco, quien present\u00f3 una disminuci\u00f3n de -2,7 puntos en su nivel de aprobaci\u00f3n.<\/p>\n\n\n\n<p>El resto de la lista del cuarto puesto en adelante lo ocupan el misionero Hugo Pasalaqua con 54,6% de positiva; el salte\u00f1o Gustavo S\u00e1enz con 54,3%; el sanjuanino Marcelo Orrego con 54,0%; el cordob\u00e9s Mart\u00edn Llaryora con 53,5%; el chubutense Ignacio Torres con 52,7%; y el correntino Juan Pablo Vald\u00e9s con 51,7%.<\/p>\n\n\n\n<p>Luego se encolumnan Maximiliano Pullaro (Santa Fe, 51,3%), Raul Jalil (Catamarca 50,9%); Octavio Frigerio (Entre R\u00edos 50,8%), El\u00edas Su\u00e1rez (Santiago del Estero 50,4%); Sergio Ziliotto (La Pampa 49,7%); Claudio Vidal (Santa Cruz 49%); Carlos Sadir (Jujuy 48,9%); Alfredo Cornejo (Mendoza 48,5%); Gustavo Melella (Tierra del Fuego 48,2%); Gildo Insfr\u00e1n (Formosa 47,1%); Jorge Macri (CABA 45,6%) y Leandro Zdero (Chaco 44,7%). #AgenciaNA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador de Neuqu\u00e9n, Rolando Figueroa, es el mandatario provincial mejor valorado por la ciudadan\u00eda, con un 56,1% de imagen positiva y -40,7% de imagen negativa, y un diferencial favorable de 54,0%, seg\u00fan una encuesta conocida este mi\u00e9rcoles. El muestreo realizado a nivel pa\u00eds por la consultora CB Global Data y al que tuvo acceso [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":86552,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[73],"tags":[],"class_list":{"0":"post-109842","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-general"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/109842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=109842"}],"version-history":[{"count":2,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/109842\/revisions"}],"predecessor-version":[{"id":109846,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/109842\/revisions\/109846"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/86552"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=109842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=109842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=109842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}