{"id":109870,"date":"2026-05-06T20:47:52","date_gmt":"2026-05-06T23:47:52","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=109870"},"modified":"2026-05-06T20:47:53","modified_gmt":"2026-05-06T23:47:53","slug":"desbarataron-a-una-banda-delictiva-de-salvador-mazza-y-recuperaron-los-objetos-robados","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2026\/05\/06\/desbarataron-a-una-banda-delictiva-de-salvador-mazza-y-recuperaron-los-objetos-robados\/","title":{"rendered":"Desbarataron a una banda delictiva de Salvador Mazza y recuperaron los objetos robados"},"content":{"rendered":"\n<p>Esta madrugada fueron detenidas cinco personas por robo calificado con uso de arma de fuego perpetrado en una finca en Tartagal. Sustrajeron una camioneta Ford Ranger, dinero en efectivo y herramientas. Se hizo un operativo candado en puntos estrat\u00e9gicos de la jurisdicci\u00f3n. R\u00e1pidamente fueron localizados y aprehendidos por efectivos del Distrito de Prevenci\u00f3n 4, a cargo de director, Marcelo Contrera.<\/p>\n\n\n\n<p>Esta madrugada, efectivos del Distrito de Prevenci\u00f3n 4 realizaron un exitoso plan candado por un robo calificado, con uso de arma de fuego, registrado en una finca ubicada en el kil\u00f3metro 8 de la ruta nacional 86, en Tartagal.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"332\" src=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-35-1024x332.png\" alt=\"\" class=\"wp-image-109872\" srcset=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-35-1024x332.png 1024w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-35-300x97.png 300w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-35-768x249.png 768w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-35-696x226.png 696w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-35-1068x346.png 1068w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-35.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>El procedimiento fue coordinado por el director del Distrito de Prevenci\u00f3n 4, Marcelo Contrera, quien dispuso un operativo candado en puntos estrat\u00e9gicos de la zona tras la alerta emitida por empleados del lugar, alrededor de las 2 de la madrugada.<\/p>\n\n\n\n<p>Del operativo participaron de manera articulada el Centro de Coordinaci\u00f3n Operativa, el centro de Videovigilancia, motoristas y el Grupo de Intervenciones Conjuntas, lo que permiti\u00f3 una r\u00e1pida respuesta y despliegue en distintas v\u00edas de circulaci\u00f3n.<\/p>\n\n\n\n<p>Hab\u00edan sustra\u00eddo una camioneta Ford Ranger, dinero en efectivo y herramientas, entre otros elementos, y se movilizaban en un auto particular Volkswagen que oficiaba como veh\u00edculo de apoyo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"770\" src=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-36-1024x770.png\" alt=\"\" class=\"wp-image-109873\" srcset=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-36-1024x770.png 1024w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-36-300x226.png 300w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-36-768x578.png 768w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-36-558x420.png 558w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-36-80x60.png 80w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-36-696x524.png 696w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-36-1068x804.png 1068w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-36-265x198.png 265w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-36.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>En el marco del operativo, la camioneta robada fue localizada en la ruta provincial 54. Sus ocupantes intentaron darse a la fuga, lo que deriv\u00f3 en una persecuci\u00f3n que culmin\u00f3 con la recuperaci\u00f3n del veh\u00edculo y la detenci\u00f3n de dos mujeres mayores de edad.<\/p>\n\n\n\n<p>Minutos despu\u00e9s, en la zona de Campo Dur\u00e1n, se intercept\u00f3 el autom\u00f3vil Volkswagen logrando la detenci\u00f3n de tres hombres. Todos los detenidos son mayores de edad, con domicilio en Salvador Mazza, y estar\u00edan vinculados entre s\u00ed.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1022\" height=\"635\" src=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-37.png\" alt=\"\" class=\"wp-image-109874\" style=\"width:1067px;height:auto\" srcset=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-37.png 1022w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-37-300x186.png 300w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-37-768x477.png 768w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-37-676x420.png 676w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-37-696x432.png 696w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-37-356x220.png 356w\" sizes=\"auto, (max-width: 1022px) 100vw, 1022px\" \/><\/figure>\n\n\n\n<p>Durante la requisa se recuperaron los elementos sustra\u00eddos y se secuestr\u00f3 m\u00e1s de un mill\u00f3n de pesos en efectivo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"567\" src=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-38-1024x567.png\" alt=\"\" class=\"wp-image-109875\" srcset=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-38-1024x567.png 1024w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-38-300x166.png 300w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-38-768x425.png 768w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-38-759x420.png 759w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-38-696x385.png 696w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-38-1068x591.png 1068w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-38.png 1070w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Intervinieron la Fiscal\u00eda Penal 2 y el Juzgado de Garant\u00edas 1 de Tartagal. La investigaci\u00f3n contin\u00faa para determinar la posible participaci\u00f3n de otras personas en el hecho.<\/p>\n\n\n\n<p>El propietario de la finca radic\u00f3 la denuncia correspondiente, mientras que los empleados del lugar reconocieron tanto los veh\u00edculos como los elementos robados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta madrugada fueron detenidas cinco personas por robo calificado con uso de arma de fuego perpetrado en una finca en Tartagal. Sustrajeron una camioneta Ford Ranger, dinero en efectivo y herramientas. Se hizo un operativo candado en puntos estrat\u00e9gicos de la jurisdicci\u00f3n. R\u00e1pidamente fueron localizados y aprehendidos por efectivos del Distrito de Prevenci\u00f3n 4, a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":109871,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[73],"tags":[],"class_list":{"0":"post-109870","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-general"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/109870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=109870"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/109870\/revisions"}],"predecessor-version":[{"id":109876,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/109870\/revisions\/109876"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/109871"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=109870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=109870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=109870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}