{"id":109977,"date":"2026-05-09T11:24:16","date_gmt":"2026-05-09T14:24:16","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=109977"},"modified":"2026-05-09T11:24:18","modified_gmt":"2026-05-09T14:24:18","slug":"el-gesto-del-muneco-gallardo-con-los-hinchas-tras-el-partido-que-su-hijo-jugo-en-salta","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2026\/05\/09\/el-gesto-del-muneco-gallardo-con-los-hinchas-tras-el-partido-que-su-hijo-jugo-en-salta\/","title":{"rendered":"El gesto del Mu\u00f1eco Gallardo con los hinchas tras el partido que su hijo jug\u00f3 en Salta"},"content":{"rendered":"\n<p>Nahuel Gallardo err\u00f3 el \u00faltimo remate de la tanda de penales y San Mart\u00edn de Tucum\u00e1n qued\u00f3 eliminado de la Copa Argentina.<\/p>\n\n\n\n<p>Marcelo Gallardo volvi\u00f3 a mostrarse en una cancha de f\u00fatbol, aunque esta vez lejos del banco de suplentes y en un rol completamente distinto: el de padre. El exentrenador de River estuvo presente en Salta para acompa\u00f1ar a su hijo Nahuel Gallardo, titular en San Mart\u00edn de Tucum\u00e1n, en el duelo ante Banfield por los 16avos de final de la Copa Argentina.<\/p>\n\n\n\n<p>El encuentro termin\u00f3 1-1 en los 90 minutos y se defini\u00f3 en penales. All\u00ed, el Taladro se impuso 5-4 en una dram\u00e1tica tanda.<\/p>\n\n\n\n<p>El momento m\u00e1s duro de la noche fue para el hijo del Mu\u00f1eco: Mauricio Sanguinetti ataj\u00f3 el remate de zurda y sentenci\u00f3 la clasificaci\u00f3n de Banfield a los octavos de final.<\/p>\n\n\n\n<p>A pesar de la frustraci\u00f3n deportiva y del golpe para su hijo, el exRiver protagoniz\u00f3 un tierno gesto con los presentes a la salida del estadio: se sac\u00f3 fotos con hinchas y accedi\u00f3 a los pedidos de la gente.<\/p>\n\n\n\n<p>Banfield, que hab\u00eda finalizado 12\u00b0 en el Grupo B del Torneo Apertura con 18 puntos, consigui\u00f3 as\u00ed avanzar de ronda. Por el lado de San Mart\u00edn de Tucum\u00e1n, el equipo dirigido por Andr\u00e9s Yllana sum\u00f3 una nueva decepci\u00f3n en la Copa Argentina, aunque pelea arriba en la Zona B de la Primera Nacional, donde actualmente se ubica cuarto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nahuel Gallardo err\u00f3 el \u00faltimo remate de la tanda de penales y San Mart\u00edn de Tucum\u00e1n qued\u00f3 eliminado de la Copa Argentina. Marcelo Gallardo volvi\u00f3 a mostrarse en una cancha de f\u00fatbol, aunque esta vez lejos del banco de suplentes y en un rol completamente distinto: el de padre. El exentrenador de River estuvo presente [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":109978,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[73],"tags":[],"class_list":{"0":"post-109977","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-general"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/109977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=109977"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/109977\/revisions"}],"predecessor-version":[{"id":109979,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/109977\/revisions\/109979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/109978"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=109977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=109977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=109977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}