{"id":110009,"date":"2026-05-09T16:37:09","date_gmt":"2026-05-09T19:37:09","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=110009"},"modified":"2026-05-09T16:37:11","modified_gmt":"2026-05-09T19:37:11","slug":"detuvieron-a-una-pareja-por-intentar-tener-sexo-en-un-avion-que-llego-a-rosario-de-panama","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2026\/05\/09\/detuvieron-a-una-pareja-por-intentar-tener-sexo-en-un-avion-que-llego-a-rosario-de-panama\/","title":{"rendered":"Detuvieron a una pareja por intentar tener sexo en un avi\u00f3n que lleg\u00f3 a Rosario de Panam\u00e1"},"content":{"rendered":"\n<p>Ocurri\u00f3 en el aeropuerto de Rosario. Los acusados tienen 55 y 60 a\u00f1os<\/p>\n\n\n\n<p>Un ins\u00f3lito episodio sali\u00f3 a la luz en las \u00faltimas horas en la provincia de Santa Fe, luego de que una pareja de pasajeros que viajaba en un vuelo internacional fuera acusada de haber intentado mantener relaciones sexuales a bordo de la aeronave.<\/p>\n\n\n\n<p>El hecho ocurri\u00f3 este s\u00e1bado en un vuelo de Copa Airlines que parti\u00f3 desde Panam\u00e1 y aterriz\u00f3 en el Aeropuerto Internacional de Rosario durante la madrugada. Seg\u00fan se inform\u00f3, los pasajeros demorados son un hombre de 55 a\u00f1os y una mujer de 60, quienes fueron encontrados semidesnudos en sus asientos, ubicados en la fila F de uno de sus vuelos.<\/p>\n\n\n\n<p>De acuerdo con fuentes cercanas al caso citadas por Infobae, ante la situaci\u00f3n, la jefa de cabina elev\u00f3 el reporte al supervisor de la compa\u00f1\u00eda a\u00e9rea y manifest\u00f3 su intenci\u00f3n de iniciar una acci\u00f3n penal por exhibicionismo.<\/p>\n\n\n\n<p>En el marco de los protocolos establecidos para este tipo de incidentes, se dio intervenci\u00f3n al Ministerio P\u00fablico de la Acusaci\u00f3n de la provincia de Santa Fe. Se indic\u00f3 que los implicados fueran entregados a la comisar\u00eda para realizar las diligencias correspondientes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ocurri\u00f3 en el aeropuerto de Rosario. Los acusados tienen 55 y 60 a\u00f1os Un ins\u00f3lito episodio sali\u00f3 a la luz en las \u00faltimas horas en la provincia de Santa Fe, luego de que una pareja de pasajeros que viajaba en un vuelo internacional fuera acusada de haber intentado mantener relaciones sexuales a bordo de la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":110010,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[73],"tags":[],"class_list":{"0":"post-110009","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-general"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/110009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=110009"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/110009\/revisions"}],"predecessor-version":[{"id":110011,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/110009\/revisions\/110011"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/110010"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=110009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=110009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=110009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}