{"id":110041,"date":"2026-05-11T12:53:26","date_gmt":"2026-05-11T15:53:26","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=110041"},"modified":"2026-05-11T12:53:28","modified_gmt":"2026-05-11T15:53:28","slug":"promesa-cumplida-y-festejo-total","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2026\/05\/11\/promesa-cumplida-y-festejo-total\/","title":{"rendered":"\u00a1Promesa cumplida y festejo total!"},"content":{"rendered":"\n<p>Un profesor de Educaci\u00f3n F\u00edsica de un colegio secundario de C\u00f3rdoba les prometi\u00f3 a sus alumnos una hora libre si en un sobre de figuritas aparec\u00eda Lionel Messi. Lo que parec\u00eda imposible termin\u00f3 ocurriendo de la manera m\u00e1s emocionante: la \u00faltima figurita del paquete era nada menos que la del capit\u00e1n argentino del Mundial 2026.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-9-16 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"youtube-embed\" data-video_id=\"\"><iframe loading=\"lazy\" title=\"\ud83d\ude4f\ud83d\ude02 \u201cSI SALE MESSI, HAY HORA LIBRE\u201d\" width=\"563\" height=\"1000\" src=\"https:\/\/www.youtube.com\/embed\/CiU1QgDHv9c?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p>La reacci\u00f3n de los estudiantes fue de pura alegr\u00eda y sorpresa, en una escena que r\u00e1pidamente se volvi\u00f3 viral por la emoci\u00f3n y la \u201cayudita\u201d del destino.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un profesor de Educaci\u00f3n F\u00edsica de un colegio secundario de C\u00f3rdoba les prometi\u00f3 a sus alumnos una hora libre si en un sobre de figuritas aparec\u00eda Lionel Messi. Lo que parec\u00eda imposible termin\u00f3 ocurriendo de la manera m\u00e1s emocionante: la \u00faltima figurita del paquete era nada menos que la del capit\u00e1n argentino del Mundial 2026. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":110042,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[73],"tags":[],"class_list":{"0":"post-110041","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-general"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/110041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=110041"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/110041\/revisions"}],"predecessor-version":[{"id":110043,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/110041\/revisions\/110043"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/110042"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=110041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=110041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=110041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}