{"id":110224,"date":"2026-05-13T13:29:22","date_gmt":"2026-05-13T16:29:22","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=110224"},"modified":"2026-05-13T13:29:22","modified_gmt":"2026-05-13T16:29:22","slug":"el-intendente-de-quijano-veto-el-aumento-en-la-dieta-de-los-concejales","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2026\/05\/13\/el-intendente-de-quijano-veto-el-aumento-en-la-dieta-de-los-concejales\/","title":{"rendered":"El intendente de Quijano veto el aumento en la dieta de los concejales"},"content":{"rendered":"\n<p>El cruce pol\u00edtico recrudeci\u00f3 esta ma\u00f1ana en Campo Quijano. El intendente Lino Yonar vet\u00f3 la resoluci\u00f3n con la que los concejales buscaban elevar sus dietas a $1.200.000 y apunt\u00f3 directamente contra los ediles por \u201cno entender la realidad que vive el municipio y la gente\u201d.<\/p>\n\n\n\n<p>La medida qued\u00f3 plasmada en la resoluci\u00f3n municipal 545\/26 y reflej\u00f3 el rechazo que el jefe comunal ya hab\u00eda adelantado en \u201cLa Llave Del Portal\u201d.<\/p>\n\n\n\n<p>\u201cLas dietas se aprueban por ordenanza y ellos hicieron una resoluci\u00f3n. Ese fue su primer error. El segundo es no entender la realidad que la gente vive hoy\u201d, dispar\u00f3 Yonar en vivo.<\/p>\n\n\n\n<p>\u201cLa jubilaci\u00f3n de un abuelo hoy ronda los 250 mil pesos y no puede ni comprar los remedios. Nosotros atendemos vecinos todos los d\u00edas y vemos la dura situaci\u00f3n econ\u00f3mica que se vive\u201d, expres\u00f3.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"731\" height=\"541\" src=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-79.png\" alt=\"\" class=\"wp-image-110225\" style=\"width:1068px;height:auto\" srcset=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-79.png 731w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-79-300x222.png 300w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-79-568x420.png 568w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-79-80x60.png 80w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-79-485x360.png 485w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-79-696x515.png 696w\" sizes=\"auto, (max-width: 731px) 100vw, 731px\" \/><\/figure>\n\n\n\n<p><strong>Lino Yonar<\/strong><\/p>\n\n\n\n<p>Seg\u00fan explic\u00f3, el municipio atraviesa una situaci\u00f3n financiera complicada y cuestion\u00f3 duramente la pretensi\u00f3n de los ediles.<\/p>\n\n\n\n<p>\u201cTodos los intendentes vemos que la coparticipaci\u00f3n no alcanza para pagar los sueldos. Entonces, \u00bfc\u00f3mo pretenden aumentarse las dietas si ni siquiera tenemos garantizado el pago de los empleados municipales ni el de ellos mismos?<\/p>\n\n\n\n<p>Hay incoherencia y egocentrismo. Solo piensan en c\u00f3mo cuidar su bolsillo y no es as\u00ed, necesitamos que entiendan la realidad y nos ayuden\u201d.<\/p>\n\n\n\n<p>Yonar cont\u00f3 que su gesti\u00f3n viene realizando ajustes y frenando compras de maquinarias para priorizar obras p\u00fablicas, servicios y funcionamiento b\u00e1sico del municipio.<\/p>\n\n\n\n<p>&#8220;Si vos concejal aprobaste un presupuesto, decime \u00bfCu\u00e1l va a ser la partida presupuestaria que pretendes que resignemos para cubrir el aumento de tu dieta? Nosotros como municipio vamos en sexta, todos los d\u00edas resolviendo problemas, gestionando recursos, golpeando puertas para traer obras y ver c\u00f3mo hacemos para pagar los sueldos.<\/p>\n\n\n\n<p>\u00bfQuieren aumento? Vengan y vean c\u00f3mo est\u00e1n las finanzas de la Municipalidad\u201d, desafi\u00f3.<\/p>\n\n\n\n<p>Si bien los concejales pueden volver a insistir, requerir\u00eda un acuerdo mayoritario en medio de un escenario pol\u00edtico quebrado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cruce pol\u00edtico recrudeci\u00f3 esta ma\u00f1ana en Campo Quijano. El intendente Lino Yonar vet\u00f3 la resoluci\u00f3n con la que los concejales buscaban elevar sus dietas a $1.200.000 y apunt\u00f3 directamente contra los ediles por \u201cno entender la realidad que vive el municipio y la gente\u201d. La medida qued\u00f3 plasmada en la resoluci\u00f3n municipal 545\/26 y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":57798,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[73],"tags":[],"class_list":{"0":"post-110224","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-general"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/110224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=110224"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/110224\/revisions"}],"predecessor-version":[{"id":110226,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/110224\/revisions\/110226"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/57798"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=110224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=110224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=110224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}