{"id":110230,"date":"2026-05-13T14:09:24","date_gmt":"2026-05-13T17:09:24","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=110230"},"modified":"2026-05-13T14:09:24","modified_gmt":"2026-05-13T17:09:24","slug":"sigue-detenida-la-mujer-que-estafo-a-57-personas-prometiendo-trabajos-mineros","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2026\/05\/13\/sigue-detenida-la-mujer-que-estafo-a-57-personas-prometiendo-trabajos-mineros\/","title":{"rendered":"Sigue detenida la mujer que estaf\u00f3 a 57 personas prometiendo trabajos mineros"},"content":{"rendered":"\n<p>Mantienen la prisi\u00f3n preventiva y ampl\u00edan a 57 los hechos de estafa atribuidos a una mujer investigada por falsas contrataciones mineras<\/p>\n\n\n\n<p>La Fiscal\u00eda sostiene que la mujer ofrec\u00eda supuestos puestos laborales vinculados al sector minero y solicitaba dinero para tr\u00e1mites y estudios preocupacionales.<\/p>\n\n\n\n<p>La mujer fue detenida el pasado 10 de marzo en el marco de una investigaci\u00f3n que lleva adelante UDEC por presuntas estafas vinculadas con ofrecimientos laborales en el sector minero.<\/p>\n\n\n\n<p>La investigaci\u00f3n de la Fiscal\u00eda se inici\u00f3 a partir de denuncias radicadas por distintas personas que manifestaron haber sido contactadas bajo la promesa de incorporarse a puestos de trabajo vinculados con proyectos mineros.<\/p>\n\n\n\n<p>En ese marco, el Cuerpo de Investigaciones Fiscales detect\u00f3 que la acusada se presentaba como profesional del \u00e1rea t\u00e9cnica, utilizando t\u00edtulos que no pudo acreditar, y ofrec\u00eda supuestas posibilidades de participaci\u00f3n en obras vinculadas con empresas del sector.<\/p>\n\n\n\n<p>Con el objetivo de otorgar apariencia de legitimidad a las maniobras investigadas, la acusada promovi\u00f3 la creaci\u00f3n y utilizaci\u00f3n de distintas estructuras comerciales, entre ellas \u201cBaez Mamani Group\u201d, \u201cRimay Group S.R.L.\u201d y \u201cConsultora Bomblin\u201d, que habr\u00edan sido utilizadas para convocar personal, emitir documentaci\u00f3n vinculada con supuestos procesos de contrataci\u00f3n y sostener la apariencia de una operatoria empresarial relacionada con proyectos mineros.<\/p>\n\n\n\n<p>Seg\u00fan la investigaci\u00f3n, a trav\u00e9s de esas firmas se convocaba a profesionales y trabajadores (entre ellos ingenieros, top\u00f3grafos y operarios) bajo la promesa de futuras contrataciones en obras presentadas como vinculadas con empresas del sector minero.<\/p>\n\n\n\n<p>En ese contexto, se habr\u00eda solicitado dinero para distintos conceptos asociados con el proceso de contrataci\u00f3n, como tr\u00e1mites administrativos y estudios preocupacionales. Los pagos se habr\u00edan realizado mediante transferencias a cuentas bancarias de terceros vinculados al grupo.<\/p>\n\n\n\n<p>La investigaci\u00f3n tambi\u00e9n involucra a otras cuatro personas vinculadas a las maniobras investigadas, cuya imputaci\u00f3n se realizar\u00e1 en los pr\u00f3ximos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mantienen la prisi\u00f3n preventiva y ampl\u00edan a 57 los hechos de estafa atribuidos a una mujer investigada por falsas contrataciones mineras La Fiscal\u00eda sostiene que la mujer ofrec\u00eda supuestos puestos laborales vinculados al sector minero y solicitaba dinero para tr\u00e1mites y estudios preocupacionales. La mujer fue detenida el pasado 10 de marzo en el marco [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":15566,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[73],"tags":[],"class_list":{"0":"post-110230","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-general"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/110230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=110230"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/110230\/revisions"}],"predecessor-version":[{"id":110232,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/110230\/revisions\/110232"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/15566"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=110230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=110230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=110230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}