{"id":110244,"date":"2026-05-13T14:43:39","date_gmt":"2026-05-13T17:43:39","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=110244"},"modified":"2026-05-13T14:43:40","modified_gmt":"2026-05-13T17:43:40","slug":"el-dueno-de-una-propiedad-de-indio-cua-declaro-que-adorni-le-pago-mas-de-us-20-mil-por-un-alquiler","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2026\/05\/13\/el-dueno-de-una-propiedad-de-indio-cua-declaro-que-adorni-le-pago-mas-de-us-20-mil-por-un-alquiler\/","title":{"rendered":"El due\u00f1o de una propiedad de Indio Cu\u00e1 declar\u00f3 que Adorni le pag\u00f3 m\u00e1s de US$ 20 mil por un alquiler"},"content":{"rendered":"\n<p>Jos\u00e9 Rodr\u00edguez declar\u00f3 ante el fiscal Pollitica y asegur\u00f3 que el funcionario permaneci\u00f3 en esa casa mientras estaba refaccionando su inmueble del country.<\/p>\n\n\n\n<p>Un nuevo testigo declar\u00f3 en el marco de la investigaci\u00f3n que atraviesa Manuel Adorni por enriquecimiento il\u00edcito: Jos\u00e9 Rodr\u00edguez, due\u00f1o de una casa del country Indio Cu\u00e1, confirm\u00f3 que el jefe de Gabinete le alquil\u00f3 la propiedad por m\u00e1s de 20.000 d\u00f3lares en efectivo, mientras refaccionaba su inmueble en ese predio de Exaltaci\u00f3n de la Cruz.<\/p>\n\n\n\n<p>Seg\u00fan el testimonio que brind\u00f3 Rodr\u00edguez, este mi\u00e9rcoles por la ma\u00f1ana, ante el fiscal federal Gerardo Pollicita, esa cifra pertenece a la suma de dos contratos de alquiler que pag\u00f3 Adorni para permanecer all\u00ed, mientras, a pocos metros, se llevaban a cabo las reformas de su propiedad por 245.000 d\u00f3lares, seg\u00fan la declaraci\u00f3n del contratista Mat\u00edas Taba<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jos\u00e9 Rodr\u00edguez declar\u00f3 ante el fiscal Pollitica y asegur\u00f3 que el funcionario permaneci\u00f3 en esa casa mientras estaba refaccionando su inmueble del country. Un nuevo testigo declar\u00f3 en el marco de la investigaci\u00f3n que atraviesa Manuel Adorni por enriquecimiento il\u00edcito: Jos\u00e9 Rodr\u00edguez, due\u00f1o de una casa del country Indio Cu\u00e1, confirm\u00f3 que el jefe de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":108808,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[59],"tags":[],"class_list":{"0":"post-110244","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/110244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=110244"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/110244\/revisions"}],"predecessor-version":[{"id":110245,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/110244\/revisions\/110245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/108808"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=110244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=110244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=110244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}