{"id":110500,"date":"2026-05-18T12:37:36","date_gmt":"2026-05-18T15:37:36","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=110500"},"modified":"2026-05-18T12:37:36","modified_gmt":"2026-05-18T15:37:36","slug":"viajaba-de-salta-a-buenos-aires-en-colectivo-con-una-mochila-con-mas-de-159-millones","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2026\/05\/18\/viajaba-de-salta-a-buenos-aires-en-colectivo-con-una-mochila-con-mas-de-159-millones\/","title":{"rendered":"Viajaba de Salta a Buenos Aires en colectivo con una mochila con m\u00e1s de $ 159 millones"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Gendarmes del Escuadr\u00f3n 55 \u201cTucum\u00e1n\u201d, llevaron adelante un control f\u00edsico y documentol\u00f3gico en la Ruta Nacional N\u00ba 9, kil\u00f3metro 1358 (Peaje Molle Yaco), en la localidad de Trancas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Interceptaron un transporte p\u00fablico de pasajeros con itinerario Salta- Buenos Aires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al inspeccionar el sector de pasajeros, los gendarmes detectaron una mochila de mano que conten\u00eda una gran cantidad de dinero en efectivo oculto.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"702\" height=\"386\" src=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-126.png\" alt=\"\" class=\"wp-image-110502\" style=\"aspect-ratio:1.8187596146061047;width:932px;height:auto\" srcset=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-126.png 702w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-126-300x165.png 300w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2026\/05\/image-126-696x383.png 696w\" sizes=\"auto, (max-width: 702px) 100vw, 702px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ante la sospecha de una maniobra il\u00edcita, se solicit\u00f3 la colaboraci\u00f3n de personal de la Unidad T\u00e9cnica de Criminal\u00edstica y Estudios Forenses \u201cTucum\u00e1n\u201d, que contabilizaron un total de 159.980.000 pesos argentinos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por disposici\u00f3n del Juzgado Federal N\u00ba 3 y la Fiscal\u00eda Federal N\u00ba 1 de Tucum\u00e1n y la Agencia de Recaudaci\u00f3n y Control Aduanero (ARCA) de la provincia, se procedi\u00f3 al secuestro del dinero y de toda la documentaci\u00f3n de inter\u00e9s para la investigaci\u00f3n, en infracci\u00f3n a la Ley 24.769.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto al propietario del equipaje, ciudadano de nacionalidad argentina, el Magistrado interviniente dispuso que contin\u00fae en libertad, supeditado a la causa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gendarmes del Escuadr\u00f3n 55 \u201cTucum\u00e1n\u201d, llevaron adelante un control f\u00edsico y documentol\u00f3gico en la Ruta Nacional N\u00ba 9, kil\u00f3metro 1358 (Peaje Molle Yaco), en la localidad de Trancas. Interceptaron un transporte p\u00fablico de pasajeros con itinerario Salta- Buenos Aires. Al inspeccionar el sector de pasajeros, los gendarmes detectaron una mochila de mano que conten\u00eda una [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":110501,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[73],"tags":[],"class_list":["post-110500","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-general"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/110500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=110500"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/110500\/revisions"}],"predecessor-version":[{"id":110503,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/110500\/revisions\/110503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/110501"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=110500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=110500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=110500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}