{"id":11557,"date":"2020-11-17T21:31:21","date_gmt":"2020-11-18T00:31:21","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=11557"},"modified":"2020-11-17T21:31:22","modified_gmt":"2020-11-18T00:31:22","slug":"el-intendente-de-embarcacion-dio-positivo-para-coronavirus","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2020\/11\/17\/el-intendente-de-embarcacion-dio-positivo-para-coronavirus\/","title":{"rendered":"El intendente de Embarcaci\u00f3n dio positivo para coronavirus"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Intendente de Embarcaci\u00f3n, Carlos Funes dio positivo para coronavirus mientras se hac\u00eda un chequeo m\u00e9dico de rutina en la capital salte\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La informaci\u00f3n fue proporcionada por la misma Municipalidad de la ciudad norte\u00f1a a trav\u00e9s del departamento de Prensa y Difusi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El jefe comunal se encuentra asintom\u00e1tico y aislado en Salta y retornar\u00e1 a Embarcaci\u00f3n cuando termine su cuarentena.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Intendente de Embarcaci\u00f3n, Carlos Funes dio positivo para coronavirus mientras se hac\u00eda un chequeo m\u00e9dico de rutina en la capital salte\u00f1a. La informaci\u00f3n fue proporcionada por la misma Municipalidad de la ciudad norte\u00f1a a trav\u00e9s del departamento de Prensa y Difusi\u00f3n. El jefe comunal se encuentra asintom\u00e1tico y aislado en Salta y retornar\u00e1 a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11558,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11557","post","type-post","status-publish","format-standard","has-post-thumbnail","category-sin-categoria"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/11557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=11557"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/11557\/revisions"}],"predecessor-version":[{"id":11559,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/11557\/revisions\/11559"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/11558"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=11557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=11557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=11557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}