{"id":19184,"date":"2021-03-16T14:47:15","date_gmt":"2021-03-16T17:47:15","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=19184"},"modified":"2021-03-16T14:48:03","modified_gmt":"2021-03-16T17:48:03","slug":"investigan-posible-extraccion-irregular-de-aridos-en-el-rio-wierna","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2021\/03\/16\/investigan-posible-extraccion-irregular-de-aridos-en-el-rio-wierna\/","title":{"rendered":"Investigan posible extracci\u00f3n irregular de \u00e1ridos en el r\u00edo Wierna"},"content":{"rendered":"\n<p>La Fiscal\u00eda Penal 1 lleva adelante actuaciones de oficio a partir de la publicaci\u00f3n de un medio de comunicaci\u00f3n digital que denunci\u00f3 que la Municipalidad de Vaqueros extrae \u00e1ridos sin autorizaci\u00f3n.<\/p>\n\n\n\n<p>El fiscal Penal 1, Juan Marcos Ezequiel Molinati, inici\u00f3 actuaciones preliminares de oficio a partir de una publicaci\u00f3n en un medio digital de Salta que denunci\u00f3 que la Municipalidad de Vaqueros extrae \u00e1ridos del r\u00edo Wierna sin autorizaci\u00f3n.<\/p>\n\n\n\n<p>Entre otras medidas, Molinati dispuso que se realice una inspecci\u00f3n ocular, croquis ilustrativo con toma de fotograf\u00edas de todos los lugares en donde se practique la extracci\u00f3n de \u00e1ridos en el r\u00edo Wierna, adem\u00e1s de tomar declaraci\u00f3n a los vecinos de la zona.<\/p>\n\n\n\n<p>El Fiscal tambi\u00e9n requiri\u00f3 al Cuerpo de Investigadores Fiscales (CIF) que realice un an\u00e1lisis f\u00edsico-qu\u00edmico de muestras -en matrices ambientales- de suelo y agua, evaluaci\u00f3n de datos y registros en materias ambientale.<\/p>\n\n\n\n<p>Adem\u00e1s -como parte de la investigaci\u00f3n- orden\u00f3 distintas diligencias, entre las que se incluyen un pedido a la Secretar\u00eda de Ambiente y Desarrollo Sustentable de la Provincia de Salta para que informe si existen permisos o autorizaciones para la extracci\u00f3n de \u00e1ridos en el r\u00edo Wierna. En caso afirmativo, que se indique qu\u00e9 personas o entidades son las autorizadas, en qu\u00e9 zona, en qu\u00e9 consiste puntualmente el permiso y qu\u00e9 tiempo de vigencia tienen dichos permisos. Tambi\u00e9n solicit\u00f3 que se informe sobre cualquier otra situaci\u00f3n vinculada la extracci\u00f3n de \u00e1ridos en la zona.<\/p>\n\n\n\n<p>Molinati tambi\u00e9n solicit\u00f3 a al titular del Ejecutivo de Vaqueros, Daniel Moreno, que informe si la Municipalidad est\u00e1 extrayendo \u00e1ridos del r\u00edo Wierna.<\/p>\n\n\n\n<p>Tambien se solicitar\u00e1n informes sobre la extracci\u00f3n de aridos en los r\u00edos Arenales, Rosario, Mojotoro y Arias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Fiscal\u00eda Penal 1 lleva adelante actuaciones de oficio a partir de la publicaci\u00f3n de un medio de comunicaci\u00f3n digital que denunci\u00f3 que la Municipalidad de Vaqueros extrae \u00e1ridos sin autorizaci\u00f3n. El fiscal Penal 1, Juan Marcos Ezequiel Molinati, inici\u00f3 actuaciones preliminares de oficio a partir de una publicaci\u00f3n en un medio digital de Salta [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":19187,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[73],"tags":[],"class_list":{"0":"post-19184","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-general"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/19184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=19184"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/19184\/revisions"}],"predecessor-version":[{"id":19186,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/19184\/revisions\/19186"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/19187"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=19184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=19184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=19184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}