{"id":23643,"date":"2021-05-24T13:10:17","date_gmt":"2021-05-24T16:10:17","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=23643"},"modified":"2021-05-24T13:10:18","modified_gmt":"2021-05-24T16:10:18","slug":"no-hay-nada-concreto-sobre-la-compra-de-vacunas-por-parte-de-salta","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2021\/05\/24\/no-hay-nada-concreto-sobre-la-compra-de-vacunas-por-parte-de-salta\/","title":{"rendered":"No hay nada concreto sobre la compra de vacunas por parte de Salta"},"content":{"rendered":"\n<p>Ayer comenz\u00f3 a circular la versi\u00f3n de que Salta estaba por comprar 1.000.000 de vacunas Johnson &amp; Johnson, y hoy el ministro de Salud, Juan Jos\u00e9 Esteban aclar\u00f3 que \u201cno hay nada concreto y que Salta siempre hizo gestiones\u201d. De esta manera el funcionario aclar\u00f3 el tema que se hab\u00eda viralizado en la jornada anterior. Dijo que en caso de que hubiera un posible acuerdo las condiciones ser\u00edan que el env\u00edo se produzca en los pr\u00f3ximos 30 d\u00edas.<\/p>\n\n\n\n<p>Cabe aclarar que en ning\u00fan lugar del pa\u00eds se aplica la vacuna Johnson &amp; Johnson y tampoco la Naci\u00f3n pudo adquirirlas hasta el momento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ayer comenz\u00f3 a circular la versi\u00f3n de que Salta estaba por comprar 1.000.000 de vacunas Johnson &amp; Johnson, y hoy el ministro de Salud, Juan Jos\u00e9 Esteban aclar\u00f3 que \u201cno hay nada concreto y que Salta siempre hizo gestiones\u201d. De esta manera el funcionario aclar\u00f3 el tema que se hab\u00eda viralizado en la jornada anterior. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23644,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[65],"tags":[],"class_list":{"0":"post-23643","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-coronavirus"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/23643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=23643"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/23643\/revisions"}],"predecessor-version":[{"id":23645,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/23643\/revisions\/23645"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/23644"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=23643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=23643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=23643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}