{"id":27697,"date":"2021-09-20T12:45:46","date_gmt":"2021-09-20T15:45:46","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=27697"},"modified":"2021-09-20T12:45:47","modified_gmt":"2021-09-20T15:45:47","slug":"condenaron-a-los-dos-acusados-por-el-doble-crimen-en-congreso","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2021\/09\/20\/condenaron-a-los-dos-acusados-por-el-doble-crimen-en-congreso\/","title":{"rendered":"Condenaron a los dos acusados por el doble crimen en Congreso"},"content":{"rendered":"\n<p>Juan Jos\u00e9 Navarro C\u00e1diz fue condenado a 45 a\u00f1os de prisi\u00f3n, mientras que Juan Jes\u00fas Fern\u00e1ndez a prisi\u00f3n perpetua.<\/p>\n\n\n\n<p>El Tribunal Oral en lo Criminal N\u00b0 9 conden\u00f3 a Juan Jos\u00e9 Navarro C\u00e1diz (27) a 45 a\u00f1os de prisi\u00f3n y a Juan Jes\u00fas Fern\u00e1ndez (45) a prisi\u00f3n perpetua por el homicidio de H\u00e9ctor Olivares y Miguel Yad\u00f3n, ocurrido en mayo del 2019 en la denominada plaza de los dos Congresos.<\/p>\n\n\n\n<p>Ambos estaban acusados de &#8220;homicidio agravado por alevos\u00eda cometido en forma reiterada en dos ocasiones, con portaci\u00f3n ilegal de arma de guerra&#8221;.<\/p>\n\n\n\n<p>Navarro C\u00e1diz fue detenido en Uruguay y, para su extradici\u00f3n, la Justicia del vecino pa\u00eds exigi\u00f3 que no fuera condenado a perpetua, por lo que durante su turno en la ronda de alegatos, el fiscal de juicio Ariel Yapur pidi\u00f3 que lo condenen a 45 a\u00f1os de prisi\u00f3n, mientras que requiri\u00f3 la pena m\u00e1xima para Fern\u00e1ndez, lo que finalmente sucedi\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juan Jos\u00e9 Navarro C\u00e1diz fue condenado a 45 a\u00f1os de prisi\u00f3n, mientras que Juan Jes\u00fas Fern\u00e1ndez a prisi\u00f3n perpetua. El Tribunal Oral en lo Criminal N\u00b0 9 conden\u00f3 a Juan Jos\u00e9 Navarro C\u00e1diz (27) a 45 a\u00f1os de prisi\u00f3n y a Juan Jes\u00fas Fern\u00e1ndez (45) a prisi\u00f3n perpetua por el homicidio de H\u00e9ctor Olivares y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":27698,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[73],"tags":[],"class_list":{"0":"post-27697","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-general"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/27697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=27697"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/27697\/revisions"}],"predecessor-version":[{"id":27699,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/27697\/revisions\/27699"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/27698"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=27697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=27697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=27697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}