{"id":37260,"date":"2022-04-14T10:41:50","date_gmt":"2022-04-14T13:41:50","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=37260"},"modified":"2022-04-14T10:41:51","modified_gmt":"2022-04-14T13:41:51","slug":"decomisan-en-aguaray-12-500-paquetes-de-cigarrillos-truchos","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2022\/04\/14\/decomisan-en-aguaray-12-500-paquetes-de-cigarrillos-truchos\/","title":{"rendered":"Decomisan en Aguaray 12.500 paquetes de cigarrillos truchos"},"content":{"rendered":"\n<p>Efectivos dependientes del Escuadr\u00f3n 54 \u201cAguaray\u201d efectuaban controles sobre un camino vecinal conocido como \u201cEl Cementerio\u201d cuando observaron un veh\u00edculo Toyota Hilux ocupado por dos ciudadanos, quienes circulaban en sentido Norte-Sur.<\/p>\n\n\n\n<p>Al advertir la presencia del personal de la Fuerza, el conductor del rodado comenz\u00f3 a realizar maniobras evasivas a fin de evitar el control e intent\u00f3 darse a la fuga.<\/p>\n\n\n\n<p>Los funcionarios lograron que el mismo detenga su marcha y tras llevar a cabo la requisa correspondiente, ante la presencia de testigos, detectaron en el interior de la camioneta 25 cajas que conten\u00edan cigarrillos extranjeros, sin el correspondiente aval legal. Totalizando 12.500 paquetes.<\/p>\n\n\n\n<p>La Fiscal\u00eda Federal de Or\u00e1n orient\u00f3 la incautaci\u00f3n de la mercader\u00eda en infracci\u00f3n a la Ley 22.415 \u201cC\u00f3digo Aduanero\u201d y que ambos involucrados queden supeditados a la causa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Efectivos dependientes del Escuadr\u00f3n 54 \u201cAguaray\u201d efectuaban controles sobre un camino vecinal conocido como \u201cEl Cementerio\u201d cuando observaron un veh\u00edculo Toyota Hilux ocupado por dos ciudadanos, quienes circulaban en sentido Norte-Sur. Al advertir la presencia del personal de la Fuerza, el conductor del rodado comenz\u00f3 a realizar maniobras evasivas a fin de evitar el control [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":37261,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[63],"tags":[],"class_list":{"0":"post-37260","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policiales"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/37260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=37260"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/37260\/revisions"}],"predecessor-version":[{"id":37262,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/37260\/revisions\/37262"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/37261"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=37260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=37260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=37260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}