{"id":37391,"date":"2022-04-18T10:39:10","date_gmt":"2022-04-18T13:39:10","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=37391"},"modified":"2022-04-18T10:39:12","modified_gmt":"2022-04-18T13:39:12","slug":"desde-hoy-vuelve-el-plan-para-comprar-motos-en-cuotas-como-acceder","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2022\/04\/18\/desde-hoy-vuelve-el-plan-para-comprar-motos-en-cuotas-como-acceder\/","title":{"rendered":"Desde hoy vuelve el plan para comprar motos en cuotas: c\u00f3mo acceder"},"content":{"rendered":"\n<p>El cr\u00e9dito se otorga a trav\u00e9s del Banco Naci\u00f3n y las tasas var\u00edan de 19,50 a 29,50 por ciento. C\u00f3mo acceder al beneficio.<\/p>\n\n\n\n<p>Tal como estaba previsto, este lunes comenz\u00f3 una nueva etapa del Plan de Financiaci\u00f3n de Motos de fabricaci\u00f3n nacional, que desde ahora se pueden adquirir en hasta 48 cuotas y a tasa subsidiada por el Estado.<\/p>\n\n\n\n<p>As\u00ed lo hab\u00eda acordado la C\u00e1mara de Fabricantes de Motoveh\u00edculos (Cafam), que re\u00fane a las principales terminales del pa\u00eds, con las c\u00e1maras de concesionarios y el Gobierno, que otorga el beneficio a trav\u00e9s del Banco Naci\u00f3n.<\/p>\n\n\n\n<p>La medida busca impulsar la compra de este tipo de veh\u00edculos, que seg\u00fan datos de la Asociaci\u00f3n de Concesionarios de Automotores (Acara) y de la propia Cafam, en marzo pasado registr\u00f3 un incremento del 30% en relaci\u00f3n al mismo mes de 2021.<\/p>\n\n\n\n<p>Desde la entidad financiera informaron que el monto m\u00e1ximo a financiar por usuario ser\u00e1 de hasta $300.000 a un plazo \u00fanico de 48 meses, con un sistema de amortizaci\u00f3n franc\u00e9s, y alcanza a todos las personas, sean clientes o no del BNA, aunque con condiciones diferentes en cada caso.<\/p>\n\n\n\n<p>Adem\u00e1s, aclararon que ese l\u00edmite no incluye los costos y gastos adicionales accesorios a la operatoria, como patentamiento, fletes y sellados, entre otros.<\/p>\n\n\n\n<p>De esta manera, una moto de $150.000 pagar\u00eda una cuota inicial de $4.180,46 en el caso de un comprador que perciba sus haberes en el BNA, mientras que para los que no son clientes, la misma ascender\u00eda a $5.322,73. En tanto, la garant\u00eda es a sola firma y se financia el 100% de la motocicleta, seg\u00fan indicaron desde la entidad oficial.<\/p>\n\n\n\n<p>Respecto a la tasa de inter\u00e9s, para quienes cobren sus haberes a trav\u00e9s del mencionado banco, la misma ser\u00e1 de 19,50%, en tanto que para el resto de los usuarios ser\u00e1 de 29,50%.<\/p>\n\n\n\n<p>\u201cMediante este plan buscamos continuar apoyando el aumento de ventas de motoveh\u00edculos de origen nacional, como se viene dando este \u00faltimo tiempo. Sin embargo, es muy importante que sigamos trabajando con el Gobierno Nacional para acordar mayores incentivos para la producci\u00f3n local para fomentar nuestra industria, y poder avanzar en los proyectos que est\u00e1n en marcha\u201d, dijo Lino Stefanuto, presidente de Cafam.<\/p>\n\n\n\n<p>El Plan Mi Moto naci\u00f3 en 2020 como un intento oficial de generar una v\u00eda de acceso facilitado a rodados, en particular en un contexto de pandemia por la llegada del coronavirus, que desalent\u00f3 el uso del transporte p\u00fablico y de ca\u00edda del consumo luego del impacto de la cuarentena sobre la actividad y el empleo.<\/p>\n\n\n\n<p>C\u00f3mo solicitar el cr\u00e9dito:<\/p>\n\n\n\n<p>La gesti\u00f3n de este beneficio se inicia a trav\u00e9s la web del Banco Naci\u00f3n, d\u00f3nde el cliente ser\u00e1 precalificado, luego podr\u00e1 reservar la motocicleta que desea mediante el link informado en el correo electr\u00f3nico, lo cual permitir\u00e1 el acceso a Tienda BNA.<\/p>\n\n\n\n<p>Una vez culminada la reserva, el interesado deber\u00e1 formalizar la solicitud del pr\u00e9stamo de forma presencial en la sucursal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cr\u00e9dito se otorga a trav\u00e9s del Banco Naci\u00f3n y las tasas var\u00edan de 19,50 a 29,50 por ciento. C\u00f3mo acceder al beneficio. Tal como estaba previsto, este lunes comenz\u00f3 una nueva etapa del Plan de Financiaci\u00f3n de Motos de fabricaci\u00f3n nacional, que desde ahora se pueden adquirir en hasta 48 cuotas y a tasa [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":37392,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[60],"tags":[],"class_list":{"0":"post-37391","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/37391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=37391"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/37391\/revisions"}],"predecessor-version":[{"id":37393,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/37391\/revisions\/37393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/37392"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=37391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=37391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=37391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}