{"id":37397,"date":"2022-04-18T10:47:44","date_gmt":"2022-04-18T13:47:44","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=37397"},"modified":"2022-04-18T10:47:45","modified_gmt":"2022-04-18T13:47:45","slug":"video-una-mujer-trastabillo-en-el-anden-cayo-debajo-del-tren-y-sobrevivio","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2022\/04\/18\/video-una-mujer-trastabillo-en-el-anden-cayo-debajo-del-tren-y-sobrevivio\/","title":{"rendered":"Video: una mujer trastabill\u00f3 en el and\u00e9n, cay\u00f3 debajo del tren y sobrevivi\u00f3"},"content":{"rendered":"\n<p>Ocurri\u00f3 en la estaci\u00f3n Independencia, del Belgrano Sur. La joven estuvo 12 d\u00edas internada en el hospital Alberto Balestrini y ya fue dada de alta. Las im\u00e1genes pueden herir su sensibilidad.<\/p>\n\n\n\n<p>Un dram\u00e1tico episodio tuvo lugar d\u00edas atr\u00e1s en la estaci\u00f3n Independencia del Belgrano Sur. Una pasajera se encontraba en el and\u00e9n y cay\u00f3 entre medio de uno de los vagones y fue socorrida por los testigos en el lugar. \u201cEstoy sorprendida de estar viva\u201d, dijo la joven.<\/p>\n\n\n\n<p>Candela pas\u00f3 12 d\u00edas internada en el hospital Alberto Balestrini con politraumatismos varios despu\u00e9s del accidente y reci\u00e9n en las \u00faltimas horas pudo ver el impactante video del que fue protagonista.<\/p>\n\n\n\n<p>&nbsp;\u201cNo le encuentro sentido, no s\u00e9 c\u00f3mo estoy viva\u201d, manifest\u00f3 en di\u00e1logo con C5N, tras recibir el alta de los m\u00e9dicos. Y a\u00f1adi\u00f3: \u201cLo \u00fanico que me acuerdo es que ped\u00eda ayuda\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"IM\u00c1GENES SENSIBLES: Una PASAJERA se CAY\u00d3 DEBAJO de una FORMACI\u00d3N de TREN y se SALV\u00d3 de MILAGRO\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/nhm4g2kNhHI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Las im\u00e1genes captadas por las c\u00e1maras de seguridad de la estaci\u00f3n muestran c\u00f3mo la joven camina tambal\u00e9andose justo cuando ingresaba una de las formaciones y, al parecer, sufre un desmayo y se desploma en el hueco entre el veh\u00edculo y el anden.<\/p>\n\n\n\n<p>Las personas que como ella esperaban la llegada del tren fueron las primeras en tratar de asistir a Candela en el lugar, tarea a la que se sum\u00f3 el Comando Trenes Seguros, perteneciente a Trenes Argentinos, desde donde llamaron a una ambulancia.<\/p>\n\n\n\n<p>\u201cPara lo que fue, es un milagro que no tenga ni un rasgu\u00f1o\u201d, insisti\u00f3 todav\u00eda sorprendida de haber salido ilesa de tan impresionante ca\u00edda. Lo cierto es que, tras ser rescatada, Candela fue trasladada al centro m\u00e9dico con politraumatismos varios y p\u00e9rdida de conocimiento, y despu\u00e9s de poco m\u00e1s de una semana fue dada de alta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ocurri\u00f3 en la estaci\u00f3n Independencia, del Belgrano Sur. La joven estuvo 12 d\u00edas internada en el hospital Alberto Balestrini y ya fue dada de alta. Las im\u00e1genes pueden herir su sensibilidad. Un dram\u00e1tico episodio tuvo lugar d\u00edas atr\u00e1s en la estaci\u00f3n Independencia del Belgrano Sur. Una pasajera se encontraba en el and\u00e9n y cay\u00f3 entre [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":37398,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[73],"tags":[],"class_list":{"0":"post-37397","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-general"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/37397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=37397"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/37397\/revisions"}],"predecessor-version":[{"id":37399,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/37397\/revisions\/37399"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/37398"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=37397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=37397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=37397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}