{"id":38609,"date":"2022-05-07T14:55:54","date_gmt":"2022-05-07T17:55:54","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=38609"},"modified":"2022-05-07T14:55:56","modified_gmt":"2022-05-07T17:55:56","slug":"otro-triple-crimen-en-rosario-sicarios-mataron-a-balazos-a-una-pareja-y-a-su-hija-de-6-anos","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2022\/05\/07\/otro-triple-crimen-en-rosario-sicarios-mataron-a-balazos-a-una-pareja-y-a-su-hija-de-6-anos\/","title":{"rendered":"Otro triple crimen en Rosario: sicarios mataron a balazos a una pareja y a su hija de 6 a\u00f1os"},"content":{"rendered":"\n<p>Las v\u00edctimas ten\u00edan 25 a\u00f1os y fueron asesinadas junto a su hija por una r\u00e1faga de tiros. Ya se registraron m\u00e1s de un centenar de homicidios en la zona.<\/p>\n\n\n\n<p>Dos j\u00f3venes de 25 a\u00f1os y su hija de 6 fueron acribillados a balazos por sicarios en un barrio de la zona sur de Rosario. Con este triple crimen, en el que se sospecha que usaron ametralladoras, la ciudad de la provincia de Santa Fe pas\u00f3 el centenar de v\u00edctimas.<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/tn.com.ar\/resizer\/gqCOM9p_G7rcVAdC5gqXMKLGsyM=\/767x0\/smart\/filters:quality(60)\/cloudfront-us-east-1.images.arcpublishing.com\/artear\/3HW26Z5KKRD55GT76FMDGXUJLY.jpg\" alt=\"Rosario se encuentra cercada por el narcotr\u00e1fico. (Foto: T\u00e9lam)\" width=\"905\" height=\"511\"\/><\/figure>\n\n\n\n<p>De acuerdo a las primeras informaciones, la familia fue baleada en la zona de Chacabuco y Garibaldi, donde los asesinos dispararon una r\u00e1faga de tiros hacia uno de los pasillos del barrio Tablada.<\/p>\n\n\n\n<p>El hombre muri\u00f3 en ese lugar pero su pareja y la nena fueron trasladadas al hospital Roque S\u00e1enz Pe\u00f1a, donde pese a los esfuerzos de los m\u00e9dicos murieron a los pocos minutos a causa de las m\u00faltiples heridas de arma de fuego.<\/p>\n\n\n\n<p>Las v\u00edctimas fueron identificadas como Rodrigo Moreyra y Mar\u00eda Altamirano, ambos de 25 a\u00f1os, y su hija Auriazul de 6 a\u00f1os.<\/p>\n\n\n\n<p>En el caso intervino personal policial, el Gabinete Criminal\u00edstico y Gendarmer\u00eda Nacional, que realiz\u00f3 las pericias hasta la madrugada del s\u00e1bado.<\/p>\n\n\n\n<p>En el lugar se encontraron varias vainas servidas y la fiscal\u00eda junto a las fuerzas de seguridad trataban de establecer los motivos del ataque.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las v\u00edctimas ten\u00edan 25 a\u00f1os y fueron asesinadas junto a su hija por una r\u00e1faga de tiros. Ya se registraron m\u00e1s de un centenar de homicidios en la zona. Dos j\u00f3venes de 25 a\u00f1os y su hija de 6 fueron acribillados a balazos por sicarios en un barrio de la zona sur de Rosario. Con [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":38610,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[63],"tags":[],"class_list":{"0":"post-38609","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policiales"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/38609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=38609"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/38609\/revisions"}],"predecessor-version":[{"id":38611,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/38609\/revisions\/38611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/38610"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=38609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=38609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=38609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}