{"id":42450,"date":"2022-07-21T10:31:11","date_gmt":"2022-07-21T13:31:11","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=42450"},"modified":"2022-07-21T10:31:27","modified_gmt":"2022-07-21T13:31:27","slug":"secuestran-232-kilos-de-coca-que-salieron-de-salta-y-jujuy-como-encomiendas","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2022\/07\/21\/secuestran-232-kilos-de-coca-que-salieron-de-salta-y-jujuy-como-encomiendas\/","title":{"rendered":"Secuestran 232 kilos de coca que salieron de Salta y Jujuy como encomiendas"},"content":{"rendered":"\n<p>Los rodados ten\u00edan como destino final las provincias de Buenos Aires, Neuqu\u00e9n y Santa Cruz.<\/p>\n\n\n\n<p>El vegetal se encontraba distribuido en 398 paquetes.<\/p>\n\n\n\n<p>Efectivos de la Secci\u00f3n Seguridad Vial \u201cArroyo Seco\u201d dependientes del Escuadr\u00f3n 46 \u201cRosario \u2013 Victoria\u201d mientras realizaban controles sobre el kil\u00f3metro 271,5 de la Ruta Nacional N\u00b0 9 (Autopista Rosario \u2013 Buenos Aires), inspeccionaron tres transportes de cargas generales procedentes de las provincias de Jujuy y Salta.<\/p>\n\n\n\n<p>Como resultado de los registros de los veh\u00edculos, los funcionarios interdictaron 28 bultos tipo encomiendas y en presencia de testigos efectuaron las aperturas de los mismos, all\u00ed detectaron 398 paquetes de hojas de coca. Se secuestr\u00f3 un total de 232 kilos del vegetal.<\/p>\n\n\n\n<p>La mercader\u00eda incautada, en infracci\u00f3n a la Ley 22.415 \u201cC\u00f3digo Aduanero, qued\u00f3 a disposici\u00f3n de la Aduana Rosario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los rodados ten\u00edan como destino final las provincias de Buenos Aires, Neuqu\u00e9n y Santa Cruz. El vegetal se encontraba distribuido en 398 paquetes. Efectivos de la Secci\u00f3n Seguridad Vial \u201cArroyo Seco\u201d dependientes del Escuadr\u00f3n 46 \u201cRosario \u2013 Victoria\u201d mientras realizaban controles sobre el kil\u00f3metro 271,5 de la Ruta Nacional N\u00b0 9 (Autopista Rosario \u2013 Buenos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":42451,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[63],"tags":[],"class_list":{"0":"post-42450","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policiales"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/42450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=42450"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/42450\/revisions"}],"predecessor-version":[{"id":42452,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/42450\/revisions\/42452"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/42451"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=42450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=42450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=42450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}