{"id":42454,"date":"2022-07-21T10:52:31","date_gmt":"2022-07-21T13:52:31","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=42454"},"modified":"2022-07-21T10:52:33","modified_gmt":"2022-07-21T13:52:33","slug":"fuerte-caida-de-las-reservas-de-viajes-hacia-el-exterior-tras-el-aumento-de-35-a-45-del-recargo-sobre-dolar-turista","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2022\/07\/21\/fuerte-caida-de-las-reservas-de-viajes-hacia-el-exterior-tras-el-aumento-de-35-a-45-del-recargo-sobre-dolar-turista\/","title":{"rendered":"Fuerte ca\u00edda de las reservas de viajes hacia el exterior tras el aumento de 35% a 45% del recargo sobre d\u00f3lar turista"},"content":{"rendered":"\n<p>Agencias de viaje aseguran que la demanda hacia afuera se fren\u00f3 y que los pasajes a\u00e9reos aumentan de precio.<\/p>\n\n\n\n<p>Luego de que el Gobierno intensificara las restricciones cambiarias para el turismo hacia el exterior y para los gastos en d\u00f3lares fuera del pa\u00eds, hay que recordar que la Administraci\u00f3n Federal de Ingresos P\u00fablicos elev\u00f3 del 35% al 45% la retenci\u00f3n impositiva para quienes hagan gastos en moneda extranjera con tarjeta de cr\u00e9dito, la demanda de viajes al exterior se desplom\u00f3, seg\u00fan aseguran fuentes del sector tur\u00edstico privado.<\/p>\n\n\n\n<p>Voceros de Travel Services aseguran que la demanda para viajar hacia el exterior cay\u00f3 en un 55% durante los d\u00edas posteriores a las nuevas medidas impulsadas por el Ministerio de Econom\u00eda. \u201cNo podemos dar certezas de que va a continuar de esta manera, pero tampoco vamos a decir que no pas\u00f3 nada\u201d, puntualizan desde la agencia de viajes.<\/p>\n\n\n\n<p>Sumado a ello, la agencia de viajes afirma que, en promedio, los pasajes a\u00e9reos desde la Argentina hacia el exterior subieron en un 7 por ciento desde que la percepci\u00f3n para gastos en d\u00f3lares con tarjeta de cr\u00e9dito subi\u00f3 un 10%. \u201cEn destinos como los Estados Unidos la suba llega a ser del 10 por ciento, mientras que hacia Madrid del 6,5 por ciento\u201d, remarcaron las fuentes.<\/p>\n\n\n\n<p>En tanto, fuentes de Despegar coincidieron al decir que \u201cen los \u00faltimos d\u00edas pudimos observar una ca\u00edda en los niveles de ventas de algunos de los destinos tur\u00edsticos m\u00e1s elegidos por los argentinos, como Miami, Madrid y R\u00edo de Janeiro\u201d.<\/p>\n\n\n\n<p>\u201cLas medidas desalientan a los argentinos a viajar por las cargas impositivas y los cambios constantes que afectan al turismo. Anuncios como el del alza del d\u00f3lar turista hacen que la presi\u00f3n fiscal que se le impone a la industria supere el 80% ya que al impuesto pa\u00eds y al 30% se le deben sumar otras cargas como el impuesto de la Direcci\u00f3n Nacional de Turismo, tasas (municipales, aeropuertos y otras), impuesto al cheque, IVA e Ingresos Brutos\u201d, sostuvo Paula Cristi, Gerente General de Despegar para Argentina y Uruguay.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Agencias de viaje aseguran que la demanda hacia afuera se fren\u00f3 y que los pasajes a\u00e9reos aumentan de precio. Luego de que el Gobierno intensificara las restricciones cambiarias para el turismo hacia el exterior y para los gastos en d\u00f3lares fuera del pa\u00eds, hay que recordar que la Administraci\u00f3n Federal de Ingresos P\u00fablicos elev\u00f3 del [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":42456,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[60],"tags":[],"class_list":{"0":"post-42454","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/42454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=42454"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/42454\/revisions"}],"predecessor-version":[{"id":42457,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/42454\/revisions\/42457"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/42456"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=42454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=42454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=42454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}