{"id":42576,"date":"2022-07-23T11:22:46","date_gmt":"2022-07-23T14:22:46","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=42576"},"modified":"2022-07-23T11:22:48","modified_gmt":"2022-07-23T14:22:48","slug":"amenaza-de-bomba-durante-un-vuelo-de-aerolineas-argentinas","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2022\/07\/23\/amenaza-de-bomba-durante-un-vuelo-de-aerolineas-argentinas\/","title":{"rendered":"Amenaza de bomba durante un vuelo de Aerol\u00edneas Argentinas"},"content":{"rendered":"\n<p>Se activ\u00f3 el protocolo de emergencia y cerraron el aeropuerto de Comodoro Rivadavia donde aterriz\u00f3 de emergencia. Iban 171 pasajeros a bordo.<\/p>\n\n\n\n<p>Un avi\u00f3n de Aerol\u00edneas Argentinas, que se dirig\u00eda rumbo a Ushuaia, recibi\u00f3 una amenaza de bomba y debi\u00f3 aterrizar de emergencia en Comodoro Rivadavia.<\/p>\n\n\n\n<p>La aeronave parti\u00f3 a las 4.46 de este s\u00e1bado desde el Aeroparque Jorge Newbery e inmediatamente se comunic\u00f3 con la torre de control de esa ciudad chubutense para dar aviso y solicitar permiso para realizar el aterrizaje.<\/p>\n\n\n\n<p>Se trata del vuelo AR 1882 que transportaba 169 pasajeros y 6 miembros de la tripulaci\u00f3n. La misma arrib\u00f3 al aeropuerto de Comodoro a las 7.40 y fue dirigido a la cabecera Este 25 donde se encontraba el personal de Bomberos, trabajadores de la ANAC, empleados de rampa de Aerol\u00edneas Argentinas y efectivos de la PSA para hacer la revisi\u00f3n del avi\u00f3n. Del operativo, adem\u00e1s, particip\u00f3 personal de Explosivos de la Polic\u00eda de la Provincia de Chubut y emergencias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se activ\u00f3 el protocolo de emergencia y cerraron el aeropuerto de Comodoro Rivadavia donde aterriz\u00f3 de emergencia. Iban 171 pasajeros a bordo. Un avi\u00f3n de Aerol\u00edneas Argentinas, que se dirig\u00eda rumbo a Ushuaia, recibi\u00f3 una amenaza de bomba y debi\u00f3 aterrizar de emergencia en Comodoro Rivadavia. La aeronave parti\u00f3 a las 4.46 de este s\u00e1bado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":42577,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[73],"tags":[],"class_list":{"0":"post-42576","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-general"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/42576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=42576"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/42576\/revisions"}],"predecessor-version":[{"id":42578,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/42576\/revisions\/42578"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/42577"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=42576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=42576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=42576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}