{"id":42587,"date":"2022-07-23T12:55:03","date_gmt":"2022-07-23T15:55:03","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=42587"},"modified":"2022-07-23T12:55:05","modified_gmt":"2022-07-23T15:55:05","slug":"boca-jugara-en-salta-contra-agropecuario-por-la-copa-america","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2022\/07\/23\/boca-jugara-en-salta-contra-agropecuario-por-la-copa-america\/","title":{"rendered":"Boca jugar\u00e1 en Salta contra Agropecuario por la copa Am\u00e9rica"},"content":{"rendered":"\n<p>Lo confirm\u00f3 el gobernador, Gustavo S\u00e1enz a trav\u00e9s de su cuenta de twitter.<\/p>\n\n\n\n<p>Esta definir la fecha en la que se llevar\u00e1 a cabo este partido entre Boca Juniors y el Club Agropecuario por los octavos de final de la Copa am\u00e9rica en el Estadio Padre Martearena.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo confirm\u00f3 el gobernador, Gustavo S\u00e1enz a trav\u00e9s de su cuenta de twitter. Esta definir la fecha en la que se llevar\u00e1 a cabo este partido entre Boca Juniors y el Club Agropecuario por los octavos de final de la Copa am\u00e9rica en el Estadio Padre Martearena.<\/p>\n","protected":false},"author":2,"featured_media":42588,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[62],"tags":[],"class_list":{"0":"post-42587","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deportes"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/42587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=42587"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/42587\/revisions"}],"predecessor-version":[{"id":42589,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/42587\/revisions\/42589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/42588"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=42587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=42587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=42587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}