{"id":45496,"date":"2022-09-16T21:34:34","date_gmt":"2022-09-17T00:34:34","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=45496"},"modified":"2022-09-16T21:34:35","modified_gmt":"2022-09-17T00:34:35","slug":"una-reconocida-empresa-de-capitalizacion-debera-devolver-mas-de-medio-millon-de-pesos-y-pagar-dano-moral-y-punitivo","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2022\/09\/16\/una-reconocida-empresa-de-capitalizacion-debera-devolver-mas-de-medio-millon-de-pesos-y-pagar-dano-moral-y-punitivo\/","title":{"rendered":"Una reconocida empresa de capitalizaci\u00f3n deber\u00e1 devolver m\u00e1s de medio mill\u00f3n de pesos y pagar da\u00f1o moral y punitivo"},"content":{"rendered":"\n<p>Un hombre y una mujer promovieron una accion en defensa del consumidor en contra de la reconocida empresa de Capitalizaci\u00f3n y Ahorro que comienza con una E y solo tiene 4 letras.<\/p>\n\n\n\n<p>La Jueza en lo Civil y Comercial de Primera Instancia de Primera Nominaci\u00f3n de Tartagal Griselda Nieto acogi\u00f3 parcialmente una demanda y conden\u00f3 a una reconocida empresa de capitalizaci\u00f3n y ahorro a pagar la suma de 550.720 pesos m\u00e1s los intereses a tasa activa del Banco Naci\u00f3n desde la fecha de recepci\u00f3n de la carta documento y hasta su efectivo pago.<\/p>\n\n\n\n<p>Conden\u00f3 a la misma empresa al pago de 70 mil pesos en concepto de da\u00f1o moral con m\u00e1s intereses calculados a tasa activa del Banco de la Naci\u00f3n Argentina y la conden\u00f3 tambi\u00e9n al pago de una suma similar en concepto de da\u00f1o punitivo en el plazo de los diez d\u00edas una vez firme la sentencia m\u00e1s los intereses a calcularse a tasa activa del Banco de la Naci\u00f3n Argentina.<\/p>\n\n\n\n<p>La acci\u00f3n fue promovida por una mujer que suscribi\u00f3 contrato con dicha empresa. La jueza se\u00f1al\u00f3 que la clienta \u201cno obtuvo la debida informaci\u00f3n al momento de suscribir los contratos\u201d y precis\u00f3 que la empresa \u201cha incumplido primordialmente con el deber calificado de informaci\u00f3n.\u201d<\/p>\n\n\n\n<p>La mujer suscribi\u00f3 en total cinco contratos o solicitudes ya que el promotor de la firma le se\u00f1al\u00f3 que esta era la mejor forma de asegurarse en el corto plazo al menos un auto cero Km.<\/p>\n\n\n\n<p>La carta documento de la mujer fue enviada en 2020.<\/p>\n\n\n\n<p>La jueza precis\u00f3 que el contrato de capitalizaci\u00f3n y de ahorro es un contrato bilateral, oneroso, con cl\u00e1usulas predispuestas y de adhesi\u00f3n y adem\u00e1s, de consumo.<\/p>\n\n\n\n<p>La finalidad principal del contrato es la de capitalizaci\u00f3n y ahorro de lo pagado mensualmente y la accesoria, aleatoria, es la adjudicaci\u00f3n de bien objeto del contrato, en este caso el autom\u00f3vil.<\/p>\n\n\n\n<p>La jueza consider\u00f3 que de la documental acompa\u00f1ada surge que se trata de un plan a 120 cuotas, es decir, a 10 diez a\u00f1os. \u201cResulta dif\u00edcil, desde la perspectiva del consumidor- suscriptor que el principal inter\u00e9s del consumidor haya sido el ahorro en un plazo de 10 a\u00f1os de la entrega del valor nominal del t\u00edtulo el que si bien no ser\u00e1 menor de lo aportado (contrato art\u00edculo 4) se ve seriamente disminuida por los efectos inflacionarios de p\u00fablico conocimiento en nuestro pa\u00eds.\u201d<\/p>\n\n\n\n<p>La empresa se promocionaba con el cartel \u201cadjudic\u00e1s y no pag\u00e1s m\u00e1s!\u201d.<\/p>\n\n\n\n<p>\u201cEs decir, es indudable para un observador com\u00fan que el principal objeto del contrato no es el ahorro por el valor nominal del t\u00edtulo sino la adquisici\u00f3n de un bien, en este caso, un autom\u00f3vil. No puede desconocerse la conducta p\u00fablica de los promotores de planes de ahorro&nbsp; y de capitalizaci\u00f3n y ahorro, de la feroz publicidad abruman a las familias consumidoras tanto sea en la v\u00eda p\u00fablica o redes sociales\u201d, apunt\u00f3 la magistrada.<\/p>\n\n\n\n<p>Cit\u00f3 la jueza la&nbsp; Resoluci\u00f3n de la Secretaria de Industria, Comercio y Miner\u00eda 906\/98 que establece que los contratos deben instrumentarse de la siguiente manera: \u201cen idioma nacional y con caracteres tipogr\u00e1ficos no inferiores a UNO CON OCHO D\u00c9CIMOS (1,8) de mil\u00edmetros de altura\u201d. Tambi\u00e9n establece que deber\u00e1n \u201cresultar f\u00e1cilmente legibles, atendiendo al contraste; formato, estilos o formas de las letras; espacios entre letras y entre l\u00edneas; sentido de la escritura, y cualquier otra caracter\u00edstica de su impresi\u00f3n\u201d.<\/p>\n\n\n\n<p>\u201cDichas disposiciones han sido francamente incumplidas por la demandada puesto que la redacci\u00f3n y confecci\u00f3n del contrato es lisa y llanamente ilegible e incomprensible para el consumidor \u2013 suscriptor. Tampoco cumple con la trascripci\u00f3n de la normativa de revocaci\u00f3n en materia de consumo y el tama\u00f1o de la fuente elegida por el proveedor es \u00ednfima, incluso m\u00e1s peque\u00f1a que la fuente del cuerpo general del contrato\u201d, puntualiz\u00f3.<\/p>\n\n\n\n<p>Record\u00f3 que \u201cel deber de informaci\u00f3n por parte del proveedor profesional es una deber calificado que constituye una obligaci\u00f3n de resultado, pues la ley exige que la misma se cumpla en determinadas condiciones, contenido expreso y en todas las etapas contractuales, incluso en la etapa previa.\u201d<\/p>\n\n\n\n<p>\u201cComprobada la falta de informaci\u00f3n adecuada y veraz al consumidor, la inclusi\u00f3n de cl\u00e1usulas abusivas, publicidad enga\u00f1osa, el da\u00f1o moral se encuentra probado. El consumidor, como ciudadano com\u00fan frente a un proveedor profesional, ve defraudadas sus expectativas cuando las condiciones de contrataci\u00f3n como las se\u00f1aladas en puntos anteriores vulneran sus derechos y son contrarias a la buena fe contractual que debe primar en las relaciones jur\u00eddicas\u201d, puntualiz\u00f3 la jueza.<\/p>\n\n\n\n<p>\u201cLa visita domiciliaria y las circunstancias de venta en la v\u00eda p\u00fablica inciden en la suscripci\u00f3n de los contratos referenciados; la falta debida de informaci\u00f3n y la venta de planes de capitalizaci\u00f3n mediante ahorros p\u00fablicos de consumidores con cl\u00e1usulas oscuras y enga\u00f1osas e incluso nulas importan una conducta reprochable en los t\u00e9rminos del art\u00edculo 52 bis de la Ley de Defensa del Consumidor\u201d!, apunt\u00f3 la jueza al analizar la procedencia del da\u00f1o punitivo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un hombre y una mujer promovieron una accion en defensa del consumidor en contra de la reconocida empresa de Capitalizaci\u00f3n y Ahorro que comienza con una E y solo tiene 4 letras. La Jueza en lo Civil y Comercial de Primera Instancia de Primera Nominaci\u00f3n de Tartagal Griselda Nieto acogi\u00f3 parcialmente una demanda y conden\u00f3 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":45497,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[73],"tags":[],"class_list":{"0":"post-45496","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-general"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/45496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=45496"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/45496\/revisions"}],"predecessor-version":[{"id":45498,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/45496\/revisions\/45498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/45497"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=45496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=45496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=45496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}