{"id":4560,"date":"2020-09-02T20:57:07","date_gmt":"2020-09-02T23:57:07","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=4560"},"modified":"2020-09-02T20:57:08","modified_gmt":"2020-09-02T23:57:08","slug":"coronavirus-en-argentina-reportan-199-nuevas-muertes-y-otros-10-933-casos-positivos","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2020\/09\/02\/coronavirus-en-argentina-reportan-199-nuevas-muertes-y-otros-10-933-casos-positivos\/","title":{"rendered":"Coronavirus en Argentina: reportan 199 nuevas muertes y otros 10.933 casos positivos"},"content":{"rendered":"\n<p>El Ministerio de Salud de la Naci\u00f3n report\u00f3 este mi\u00e9rcoles&nbsp;199 nuevas muertes y otros 10.933&nbsp;casos positivos&nbsp;de&nbsp;<a href=\"https:\/\/www.clarin.com\/tema\/coronavirus-en-argentina.html\" target=\"_blank\" rel=\"noreferrer noopener\">coronavirus&nbsp;<\/a>en todo el pa\u00eds. As\u00ed, Argentina super\u00f3 una nueva barrera y lleg\u00f3 a los&nbsp;s 9.118&nbsp;fallecidos por la enfermedad. En tanto, ya se acumulan&nbsp;439.172 contagios.&nbsp;<\/p>\n\n\n\n<p>En su parte matutino, la cartera sanitaria hab\u00eda&nbsp;<a href=\"https:\/\/www.clarin.com\/sociedad\/confirman-52-nuevas-muertes-coronavirus-ultimas-12-horas_0_azXUV4Lgo.html\" target=\"_blank\" rel=\"noreferrer noopener\">confirmado 52 v\u00edctimas fatales&nbsp;<\/a>(32 hombres y 20 mujeres), de las cuales 34 resid\u00edan en la provincia de Buenos Aires, seis en la Ciudad de Buenos Aires (CABA), cinco en Jujuy, tres en Tierra del Fuego y una en Mendoza, R\u00edo Negro, C\u00f3rdoba y Santa Fe.<\/p>\n\n\n\n<p>Por la noche se sumaron&nbsp;otros 147 decesos&nbsp;(87 hombres y 60 mujeres), de los cuales 75 pertenecieron a Provincia, 41 a Capital Federal, seis de Jujuy y R\u00edo Negro, cinco de Entre R\u00edos, cuatro de C\u00f3rdoba, tres de Mendoza, dos de Santa Fe, y uno de Salta y Santa Cruz.<\/p>\n\n\n\n<p>La tasa de letalidad sobre los casos confirmados es del 2,1% y la mortalidad espec\u00edfica es de 197 personas por cada mill\u00f3n de habitantes, con una edad media de las personas fallecidas de&nbsp;72 a\u00f1os.<\/p>\n\n\n\n<p>Durante el reporte se se\u00f1al\u00f3 que entre los pacientes mayores de 70 a\u00f1os la mortalidad ronda el 15%, al tiempo que el 80% de las muertes corresponden a personas de m\u00e1s de 60 a\u00f1os.<\/p>\n\n\n\n<p>De los nuevos contagios, 6.235 se reportaron en la provincia de Buenos Aires, el distrito m\u00e1s afectado del territorio nacional, con 271.185 positivos, casi el 62% de los casos registrados hasta ahora.<\/p>\n\n\n\n<p>Por su parte, la Ciudad de Buenos Aires inform\u00f3 otros 1.346 positivos y qued\u00f3 a un paso de los 100 mil (98.345).<\/p>\n\n\n\n<p>En el interior del pa\u00eds, hubo un nuevo salto en la curva de casos en Santa Fe (747), C\u00f3rdoba (480), Mendoza (413), Tucum\u00e1n (324) y Jujuy (318).<\/p>\n\n\n\n<p>Por encima de los cien contagios diarios tambi\u00e9n se ubicaron Entre R\u00edos (188), cuyo&nbsp;<a href=\"https:\/\/www.clarin.com\/politica\/gustavo-bordet-gobernador-rios-dio-positivo-coronavirus_0_Wq_pW7vAS.html\" target=\"_blank\" rel=\"noreferrer noopener\">gobernador Gustavo Bordet dio positivo<\/a>, Salta (184), R\u00edo Negro (173) y Santa Cruz (107).<\/p>\n\n\n\n<p>El resto de los casos de las jornada se repartieron entre Neuqu\u00e9n (91), Chaco (84), La Rioja (67), Santiago del Estero (55), Tierra del Fuego (33), San Juan (32), Chubut (28), San Luis (21), Corrientes (7), Formosa (1) y La Pampa (1).<\/p>\n\n\n\n<p>Las \u00fanicas provincias que no reportaron contagios en las \u00faltimas horas fueron Catamarca y Misiones que, sumadas a Formosa, son los \u00fanicos distritos del pa\u00eds que a\u00fan no superaron los cien infectados.<\/p>\n\n\n\n<p>De acuerdo a la informaci\u00f3n oficial, el martes fueron hechos 23.115 testeos y desde el inicio del brote se realizaron 1.300.866 pruebas diagn\u00f3sticas para esta enfermedad, lo que equivale a 28.668,1 muestras por mill\u00f3n de habitantes.<\/p>\n\n\n\n<p>La secretaria de Acceso a la Salud,&nbsp;Carla Vizzotti, record\u00f3 que la edad media de los nuevos contagios es de 38 a\u00f1os, &#8220;ese grupo etario de personas j\u00f3venes, que tienen actividad porque tiene la responsabilidad de trabajar en las actividades exceptuadas y con protocolo&#8221;.<\/p>\n\n\n\n<p>Por otra parte, remarc\u00f3 que el n\u00famero de personas internadas en terapia intensiva&nbsp;est\u00e1 creciendo \u201ca expensas de las provincias&nbsp;que est\u00e1n aumentando la cantidad de casos&#8221;.<\/p>\n\n\n\n<p>&#8220;Estamos siguiendo m\u00e1s de cerca algunos distritos como R\u00edo Negro, con una ocupaci\u00f3n del 67%; Mendoza, con el 64%; o Jujuy, con el 71%&#8221;, a\u00f1adi\u00f3 el titular de la Secretar\u00eda de Calidad en Salud,&nbsp;Arnaldo Medina.<\/p>\n\n\n\n<p>De todos modos, indic\u00f3 que esas provincias tienen zonas especialmente comprometidas &#8220;en el l\u00edmite de su capacidad&#8221; y refiri\u00f3 a General Roca y Cipoletti, en R\u00edo Negro, que ya est\u00e1n en un 100% de ocupaci\u00f3n de camas, as\u00ed como la ciudad de Mendoza y el gran Mendoza, que ronda el 90%; y San Salvador de Jujuy.<\/p>\n\n\n\n<p>Tanto Medina como Vizzotti se refirieron al estado de&nbsp;fatiga del personal de salud: &#8220;Est\u00e1n agotados, muy cansados, sobre todo en las zonas con mayor cantidad de ocupaci\u00f3n de camas&#8221;, se\u00f1al\u00f3 la funcionaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio de Salud de la Naci\u00f3n report\u00f3 este mi\u00e9rcoles&nbsp;199 nuevas muertes y otros 10.933&nbsp;casos positivos&nbsp;de&nbsp;coronavirus&nbsp;en todo el pa\u00eds. As\u00ed, Argentina super\u00f3 una nueva barrera y lleg\u00f3 a los&nbsp;s 9.118&nbsp;fallecidos por la enfermedad. En tanto, ya se acumulan&nbsp;439.172 contagios.&nbsp; En su parte matutino, la cartera sanitaria hab\u00eda&nbsp;confirmado 52 v\u00edctimas fatales&nbsp;(32 hombres y 20 mujeres), de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4561,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[65],"tags":[],"class_list":{"0":"post-4560","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-coronavirus"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/4560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=4560"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/4560\/revisions"}],"predecessor-version":[{"id":4562,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/4560\/revisions\/4562"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/4561"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=4560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=4560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=4560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}