{"id":4710,"date":"2020-09-03T21:23:51","date_gmt":"2020-09-04T00:23:51","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=4710"},"modified":"2020-09-03T21:23:52","modified_gmt":"2020-09-04T00:23:52","slug":"de-la-estratosfera-a-la-pantalla-chica-carlos-menem-tendra-una-miniserie-con-su-vida","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2020\/09\/03\/de-la-estratosfera-a-la-pantalla-chica-carlos-menem-tendra-una-miniserie-con-su-vida\/","title":{"rendered":"De la estrat\u00f3sfera a la pantalla chica: Carlos Menem tendr\u00e1 una miniserie con su vida"},"content":{"rendered":"\n<p>La biopic del ex presidente estar\u00e1 ambientada en la d\u00e9cada del noventa, cuando estuvo al mando del pa\u00eds. Se lanzar\u00eda en 2021.<\/p>\n\n\n\n<p>De un tiempo a esta parte, con la llegada de las plataformas de streaming los documentales de las vidas de famosos, deportistas y pol\u00edticos han copado las pantallas. Ahora, las productoras Yulgok Media, de Estados Unidos, y Claxson Group llevar\u00e1n la vida de la familia de&nbsp;<a href=\"https:\/\/twitter.com\/zulemitamenem\" target=\"_blank\" rel=\"noreferrer noopener\">Carlos Menem<\/a>&nbsp;a una ficci\u00f3n.<\/p>\n\n\n\n<p>mbas productoras consiguieron los derechos exclusivos, que fueron otorgados por la familia del ex presidente que tiene 90 a\u00f1os.<\/p>\n\n\n\n<p>Todo estar\u00e1 ambientado en la d\u00e9cada de los \u00b490, ser\u00e1 un thriller pol\u00edtico mezclado con comedia dram\u00e1tica. Al parecer la emitir\u00e1 Amazon y&nbsp;Zulemita, hija del ex mandatario, confirm\u00f3 que formar\u00e1 parte de esta producci\u00f3n.<\/p>\n\n\n\n<p>El proyecto se llamar\u00e1 \u201c\u00a1S\u00edganme!\u201d, por su famosa frase de campa\u00f1a \u201cSiganme, que no los voy a defraudar\u201d, que hasta marc\u00f3 todo una \u00e9poca. A\u00fan se desconoce qu\u00e9 actores ser\u00e1n de la partida.<\/p>\n\n\n\n<p>El ex presidente supo codearse con grandees figuras del mundo del espect\u00e1culos y, claramente de la pol\u00edtica. Tuvo mucha afinidad con el presidente de Estados Unidos&nbsp;George Bush y Bill Clinton, adem\u00e1s de amistad con&nbsp;Diego Maradona, recibi\u00f3 a los Rolling Stone en la Quinta de Olivos en 1995. Estuvo con&nbsp;Charly Garc\u00eda, Pel\u00e9, Michael Jackson&nbsp;entre tantos otros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La biopic del ex presidente estar\u00e1 ambientada en la d\u00e9cada del noventa, cuando estuvo al mando del pa\u00eds. Se lanzar\u00eda en 2021. De un tiempo a esta parte, con la llegada de las plataformas de streaming los documentales de las vidas de famosos, deportistas y pol\u00edticos han copado las pantallas. Ahora, las productoras Yulgok Media, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4711,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[120],"tags":[],"class_list":{"0":"post-4710","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-espectaculos-2"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/4710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=4710"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/4710\/revisions"}],"predecessor-version":[{"id":4712,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/4710\/revisions\/4712"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/4711"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=4710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=4710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=4710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}