{"id":4716,"date":"2020-09-04T10:15:40","date_gmt":"2020-09-04T13:15:40","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=4716"},"modified":"2020-09-04T10:15:41","modified_gmt":"2020-09-04T13:15:41","slug":"vergonzoso-ocurrio-en-oran-una-persona-fallecio-y-su-cuerpo-estuvo-4-horas-tirado-en-el-piso-hasta-que-fueron-a-retirarlo","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2020\/09\/04\/vergonzoso-ocurrio-en-oran-una-persona-fallecio-y-su-cuerpo-estuvo-4-horas-tirado-en-el-piso-hasta-que-fueron-a-retirarlo\/","title":{"rendered":"Vergonzoso: ocurri\u00f3 en Or\u00e1n una persona falleci\u00f3 y su cuerpo estuvo 4 horas tirado en el piso hasta que fueron a retirarlo"},"content":{"rendered":"\n<p>Ayer jueves alrededor de las 16 horas, una persona perdi\u00f3 la vida en la puerta de su vivienda en barrio Caballito de Or\u00e1n, y su cuerpo estuvo en el piso al lado de su auto por mas de 4 horas.<\/p>\n\n\n\n<p>Seg\u00fan se pudo averiguar, los vecinos llamaron al sistema de emergencias 911, llegando al lugar un m\u00f3vil policial con dos efectivos, y despues de transcurrido una hora se fueron, tambi\u00e9n lleg\u00f3 una ambulancia donde tampoco levantaron el cuerpo y retiraron.<\/p>\n\n\n\n<p>Los vecinos denuncian que volvieron a llamar al 911, pero le respondieron &#8220;ustedes no son la \u00fanica familia que tienen un familiar muerto en su casa&#8221;.<\/p>\n\n\n\n<p>Por \u00faltimo, hay diferentes versiones sobre el deceso de este masculino, unos dicen que ten\u00eda s\u00edntomas de COVID-19, habr\u00eda concurrido a la guardia para una atenci\u00f3n y lo mandaron a su casa a tomar medicamentos ya que no se est\u00e1n realizando los hisopados. Y otros vecinos cuentan que sufri\u00f3 un paro cardiorespiratorio y que no ten\u00eda s\u00edntomas de coronavirus.<\/p>\n\n\n\n<p>Fuente: La D\u00edez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ayer jueves alrededor de las 16 horas, una persona perdi\u00f3 la vida en la puerta de su vivienda en barrio Caballito de Or\u00e1n, y su cuerpo estuvo en el piso al lado de su auto por mas de 4 horas. Seg\u00fan se pudo averiguar, los vecinos llamaron al sistema de emergencias 911, llegando al lugar [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4717,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[73],"tags":[],"class_list":{"0":"post-4716","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-general"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/4716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=4716"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/4716\/revisions"}],"predecessor-version":[{"id":4718,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/4716\/revisions\/4718"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/4717"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=4716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=4716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=4716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}