{"id":4866,"date":"2020-09-06T19:04:39","date_gmt":"2020-09-06T22:04:39","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=4866"},"modified":"2020-09-06T19:04:39","modified_gmt":"2020-09-06T22:04:39","slug":"oran-enorme-caravana-y-cacerolazo-en-reclamo-del-deficiente-sistema-sanitario","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2020\/09\/06\/oran-enorme-caravana-y-cacerolazo-en-reclamo-del-deficiente-sistema-sanitario\/","title":{"rendered":"Or\u00e1n: enorme caravana y cacerolazo en reclamo del deficiente sistema sanitario"},"content":{"rendered":"\n<p>Convocados por redes sociales, los oranenses se manifestaron anoche con una caravana y un masivo cacerolazo preocupados por la grave situaci\u00f3n epidemiol\u00f3gica por la que atraviesa el departamento.<\/p>\n\n\n\n<p>Entre los puntos principales del reclamo se encuentran, \u201cla falta de funcionamiento de la escuela Osvaldo Pos, solicitando donadores de plasma y para que no falte atenci\u00f3n ni medicaci\u00f3n para pacientes internados\u201d.<\/p>\n\n\n\n<p>En la semana estuvieron desde el gobernador S\u00e1enz hasta un alto funcionario del Ministerio de Salud de la Naci\u00f3n, pero los anuncios no llevaron tranquilidad por un descreimiento generalizado y fallas en la comunicaci\u00f3n de las autoridades.<\/p>\n\n\n\n<p>Los datos de los \u00faltimos d\u00edas contribuyeron a esta expresi\u00f3n popular de una sociedad que, en su gran mayor\u00eda ve\u00eda como lejano el coronavirus. Una demostraci\u00f3n de eso es que hasta hace algunos d\u00edas, tambi\u00e9n las redes sociales, mostraban una gran cantidad de reuniones sociales o familiares, personas aglomeradas en comercios o bancos, entre otras actitudes que recib\u00edan cuestionamiento de lo m\u00e1s responsables.<\/p>\n\n\n\n<p>Solo ayer 47 casos fueron notificados en Or\u00e1n y 7 v\u00edctimas fatales.<\/p>\n\n\n\n<p>Desde el inicio de pandemia, la ciudad sum\u00f3 486 casos y 41 personas perdieron la vida.<\/p>\n\n\n\n<p><strong>Luces de Alarma<\/strong><\/p>\n\n\n\n<p>Hoy el intendente de la Ciudad Pablo Gonz\u00e1lez, apareci\u00f3 en todos los medios de difusi\u00f3n con el fin de bajar la tensi\u00f3n existente en la ciudad luego de la caravana y cacerolazo y afirmo que hay las luces de alarma, dando entender la delicada situaci\u00f3n que afronta la Ciudad y el departamento.<\/p>\n\n\n\n<p>Dijo que el 80 % de las camas est\u00e1n ocupadas con pacientes Covid, y que el martes reci\u00e9n la Escuela Osvaldo Pos estar\u00eda acondicionada con 25 camas y con el personal necesario.<\/p>\n\n\n\n<p>Afirm\u00f3 que hoy una empresa estuvo trabajando para dejar en condiciones el sistema de oxigeno central en el Hospital San Vicente de Paul.<\/p>\n\n\n\n<p>Anunci\u00f3 tambi\u00e9n que ma\u00f1ana agentes sanitarios y empleados municipales afectados a las tareas del dengue saldr\u00e1n a los barrios a detectar pacientes sintom\u00e1ticos y al detectarse casos sospechosos ser\u00e1n hisopados y aislados en la Escuela Osvaldo Pos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Convocados por redes sociales, los oranenses se manifestaron anoche con una caravana y un masivo cacerolazo preocupados por la grave situaci\u00f3n epidemiol\u00f3gica por la que atraviesa el departamento. Entre los puntos principales del reclamo se encuentran, \u201cla falta de funcionamiento de la escuela Osvaldo Pos, solicitando donadores de plasma y para que no falte atenci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4867,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[69],"tags":[],"class_list":{"0":"post-4866","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-salta"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/4866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=4866"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/4866\/revisions"}],"predecessor-version":[{"id":4868,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/4866\/revisions\/4868"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/4867"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=4866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=4866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=4866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}