{"id":5052,"date":"2020-09-07T20:37:49","date_gmt":"2020-09-07T23:37:49","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=5052"},"modified":"2020-09-07T20:37:50","modified_gmt":"2020-09-07T23:37:50","slug":"coronavirus-tras-171-dias-de-cuarentena-argentina-supero-las-10-000-muertes","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2020\/09\/07\/coronavirus-tras-171-dias-de-cuarentena-argentina-supero-las-10-000-muertes\/","title":{"rendered":"Coronavirus: tras 171 d\u00edas de cuarentena, Argentina super\u00f3 las 10.000 muertes"},"content":{"rendered":"\n<p>El Ministerio de Salud de la Naci\u00f3n inform\u00f3 este lunes que durante las \u00faltimas 24 horas se registraron 271 muertes y 9.215 nuevos casos positivos por coronavirus.&nbsp;Tras casi seis meses de cuarentena, el total de infectados en todo el pa\u00eds asciende a 488.007 y las v\u00edctimas fatales suman 10.129.<\/p>\n\n\n\n<p>La ocupaci\u00f3n de camas de terapia intensiva a nivel nacional es de 61,9% y en el AMBA -foco de la enfermedad- es del 67,8%, un porcentaje que no vari\u00f3 demasiado en las \u00faltimas dos semanas.<\/p>\n\n\n\n<p>Evoluci\u00f3n de la tasa de mortalidad<\/p>\n\n\n\n<p>El 14 de abril, 38 d\u00edas despu\u00e9s del primer fallecido en el pa\u00eds, Argentina&nbsp;<a href=\"https:\/\/www.infobae.com\/coronavirus\/2020\/04\/14\/coronavirus-en-la-argentina-los-numeros-detras-de-las-primeras-100-muertes\/\">superaba los 100 muertos por coronavirus<\/a>. Llegar a las primeras&nbsp;<a href=\"https:\/\/www.infobae.com\/sociedad\/2020\/06\/21\/a-110-dias-del-primer-caso-como-crecieron-las-victimas-fatales-y-como-evoluciono-la-enfermedad\/\">1.000 v\u00edctimas fatales por Covid le demand\u00f3 68 d\u00edas m\u00e1s<\/a>, se contabiliz\u00f3 ese n\u00famero el 21 de junio \u00faltimo. El n\u00famero se multiplic\u00f3 por 10 en 78 d\u00edas y&nbsp;hoy los muertos alcanzaron los 10.000.<\/p>\n\n\n\n<p>Este n\u00famero ubica al pa\u00eds en el puesto 16 sobre una lista de 150 pa\u00edses, cuyos fallecimientos informa diariamente la Universidad Johns Hopkins de Estados Unidos.<\/p>\n\n\n\n<p>Si bien en m\u00e1s del 80% de los casos el coronavirus se caracteriza por tener una evoluci\u00f3n favorable y s\u00edntomas leves,&nbsp;el crecimiento sostenido y exponencial de contagios se tradujo en un crecimiento de las muertes.<\/p>\n\n\n\n<p>Con un promedio de 53 decesos por jornada desde el primer caso, el ritmo de nuevos fallecimientos diarios se duplic\u00f3 en los \u00faltimos 20 d\u00edas.<\/p>\n\n\n\n<p>Sin embargo, la cantidad de nuevos decesos por Covid que informan diariamente las autoridades sanitarias nacionales&nbsp;no refleja con exactitud los fallecimientos producidos en las \u00faltimas 24 horas.<\/p>\n\n\n\n<p>Tal&nbsp;<a href=\"https:\/\/www.infobae.com\/politica\/2020\/08\/23\/muertos-por-coronavirus-por-el-retraso-en-la-carga-de-datos-las-cifras-de-hoy-son-una-foto-vieja\/\">como cont\u00f3 Infobae<\/a>, dos investigadores argentinos independientes, Federico Tiberti y Mauro Infantino, detectaron que la cantidad de muertos reportados por d\u00eda en los partes oficiales no coincide con las fechas de fallecimiento consignadas de los pacientes en la base de datos abierta de la cartera sanitaria nacional, de actualizaci\u00f3n diaria.<\/p>\n\n\n\n<p>Este an\u00e1lisis -realizado a partir del dise\u00f1o de un algoritmo que permite seguir la ruta de cada contagiado en ese conjunto de datos- dej\u00f3 al descubierto que&nbsp;<a href=\"https:\/\/www.infobae.com\/politica\/2020\/08\/25\/muertos-por-coronavirus-de-las-382-muertes-informadas-ayer-casi-la-mitad-ocurrieron-hace-mas-de-10-dias\/\">hay retrasos en la carga de los fallecidos de m\u00e1s 10 d\u00edas<\/a>, con decesos que incluso superan ese lapso. Seg\u00fan sus hallazgos, el caso m\u00e1s extremo fue el de una mujer de 85 a\u00f1os, residente en la provincia de Buenos Aires, que falleci\u00f3 el 17 de abril y cuya muerte fue registrada en el sistema reci\u00e9n 116 d\u00edas despu\u00e9s: el 11 de agosto.<\/p>\n\n\n\n<p>M\u00e1s all\u00e1 del n\u00famero total de fallecidos por coronavirus, los expertos recomiendan analizar la&nbsp;tasa de letalidad, un indicador que se calcula a partir de la cantidad de muertos respecto de los casos positivos detectados, y que refleja en cierta medida la virulencia de una enfermedad, y la fortaleza del sistema sanitario para hacerle frente.<\/p>\n\n\n\n<p>En&nbsp;Argentina la tasa de letalidad es del 2%.&nbsp;Esto significa que&nbsp;de cada 100 confirmados, 2 pierden la vida por la enfermedad&nbsp;o complicaciones derivadas de ella. En este resultado influyen no solo la capacidad y calidad de la asistencia, sino tambi\u00e9n la edad de los pacientes y las enfermedades de base preexistentes. Es un indicador nacional que se viene manteniendo estable a lo largo de la pandemia.<\/p>\n\n\n\n<p>La provincia que registra mayor cantidad de decesos es Buenos Aires, con 6155 fallecidos; y le siguen CABA con 2440 y Jujuy con 257.<\/p>\n\n\n\n<p>En cuanto a la letalidad, seg\u00fan los \u00faltimos datos informados anoche por el Ministerio de Salud, Chaco tiene el doble de letalidad que la media nacional: casi 4 fallecimientos cada 100 casos. Y por encima de la media nacional tambi\u00e9n se ubican La Rioja, Misiones, R\u00edo Negro y Jujuy con valores cercanos a los 3 muertos por cada 100 positivos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio de Salud de la Naci\u00f3n inform\u00f3 este lunes que durante las \u00faltimas 24 horas se registraron 271 muertes y 9.215 nuevos casos positivos por coronavirus.&nbsp;Tras casi seis meses de cuarentena, el total de infectados en todo el pa\u00eds asciende a 488.007 y las v\u00edctimas fatales suman 10.129. La ocupaci\u00f3n de camas de terapia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5053,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[65],"tags":[],"class_list":{"0":"post-5052","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-coronavirus"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/5052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=5052"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/5052\/revisions"}],"predecessor-version":[{"id":5054,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/5052\/revisions\/5054"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/5053"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=5052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=5052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=5052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}