{"id":50950,"date":"2023-01-03T12:42:17","date_gmt":"2023-01-03T15:42:17","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=50950"},"modified":"2023-01-03T12:42:19","modified_gmt":"2023-01-03T15:42:19","slug":"3-menores-detenidos-en-ciudad-del-milagro-por-robar-perfumes-y-desodorantes","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2023\/01\/03\/3-menores-detenidos-en-ciudad-del-milagro-por-robar-perfumes-y-desodorantes\/","title":{"rendered":"3 menores detenidos en Ciudad del Milagro por robar perfumes y desodorantes"},"content":{"rendered":"\n<p>Tres j\u00f3venes de 15, 16 y 17 a\u00f1os fueron detenidos esta madrugada por robar en un local comercial de ciudad del Milagro.<\/p>\n\n\n\n<p>Efectivos de Comisaria Sexta lograron recuperar los elementos sustra\u00eddos por los menores que fueron puestos a disposici\u00f3n de la justicia.<\/p>\n\n\n\n<p>Pasadas las 04:30 de hoy un llamado al Sistema de Emergencias 911 alert\u00f3 sobre un grupo de personas provocando da\u00f1os en un local de cosm\u00e9ticos ubicado en barrio Ciudad del Milagro en zona norte de la ciudad.<\/p>\n\n\n\n<p>El personal de Comisaria Sexta se desplaz\u00f3 de inmediato al lugar, logrando la demora de los presuntos causantes, trat\u00e1ndose de tres adolescentes quienes fueron r\u00e1pidamente aprehendidos y ten\u00edan en su poder perfumes, desodorantes y otros elementos sustra\u00eddos.<\/p>\n\n\n\n<p>Por el hecho tres j\u00f3venes de 15, 16 y 17 a\u00f1os quedaron junto al secuestro a disposici\u00f3n de la justicia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tres j\u00f3venes de 15, 16 y 17 a\u00f1os fueron detenidos esta madrugada por robar en un local comercial de ciudad del Milagro. Efectivos de Comisaria Sexta lograron recuperar los elementos sustra\u00eddos por los menores que fueron puestos a disposici\u00f3n de la justicia. Pasadas las 04:30 de hoy un llamado al Sistema de Emergencias 911 alert\u00f3 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":50951,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[63],"tags":[],"class_list":{"0":"post-50950","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policiales"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/50950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=50950"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/50950\/revisions"}],"predecessor-version":[{"id":50952,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/50950\/revisions\/50952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/50951"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=50950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=50950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=50950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}