{"id":51590,"date":"2023-01-17T13:13:35","date_gmt":"2023-01-17T16:13:35","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=51590"},"modified":"2023-01-17T13:13:37","modified_gmt":"2023-01-17T16:13:37","slug":"hubo-231-casos-de-covid-y-3-muertos-en-la-ultima-semana-en-salta","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2023\/01\/17\/hubo-231-casos-de-covid-y-3-muertos-en-la-ultima-semana-en-salta\/","title":{"rendered":"Hubo 231 casos de Covid y 3 muertos en la \u00faltima semana en Salta"},"content":{"rendered":"\n<p>La Direcci\u00f3n General de Coordinaci\u00f3n Epidemiol\u00f3gica del Ministerio de Salud P\u00fablica, dio a conocer un informe sobre la segunda semana epidemiol\u00f3gica, comprendida entre el 8 y el 14 de enero, en el cual se incluyen los siguientes datos:<\/p>\n\n\n\n<p>En la semana epidemiol\u00f3gica 2 (SE2), se notificaron 231 casos de COVID-19, de los cuales 121 corresponden al departamento Capital. Otros departamentos, con 10 o m\u00e1s casos son:<\/p>\n\n\n\n<p>\u00b7San Mart\u00edn: 17<\/p>\n\n\n\n<p>\u00b7Santa Victoria: 14<\/p>\n\n\n\n<p>\u00b7Rosario de Lerma: 12<\/p>\n\n\n\n<p>Otros departamentos:<\/p>\n\n\n\n<p>\u00b7Anta: 9<\/p>\n\n\n\n<p>\u00b7Cachi: 2<\/p>\n\n\n\n<p>\u00b7Cafayate: 0<\/p>\n\n\n\n<p>\u00b7Cerrillos: 5<\/p>\n\n\n\n<p>\u00b7Chicoana: 2<\/p>\n\n\n\n<p>\u00b7General G\u00fcemes: 9<\/p>\n\n\n\n<p>\u00b7Guachipas: 0<\/p>\n\n\n\n<p>\u00b7Iruya: 0<\/p>\n\n\n\n<p>\u00b7La Caldera: 5<\/p>\n\n\n\n<p>\u00b7La Candelaria: 1<\/p>\n\n\n\n<p>\u00b7La Poma: 3<\/p>\n\n\n\n<p>\u00b7La Vi\u00f1a: 7<\/p>\n\n\n\n<p>\u00b7Los Andes: 4<\/p>\n\n\n\n<p>\u00b7Met\u00e1n: 2<\/p>\n\n\n\n<p>\u00b7Molinos: 4<\/p>\n\n\n\n<p>\u00b7Or\u00e1n: 2<\/p>\n\n\n\n<p>\u00b7Rivadavia: 0<\/p>\n\n\n\n<p>\u00b7Rosario de la Frontera: 6<\/p>\n\n\n\n<p>\u00b7San Carlos: 6<\/p>\n\n\n\n<p>En este periodo se registraron tres defunciones por COVID-19, lo que lleva la cifra total de decesos, desde el inicio de la pandemia, a 3507.<\/p>\n\n\n\n<p>Enfermedades transmitidas por alimentos (ETA)<\/p>\n\n\n\n<p>En el per\u00edodo mencionado hubo 42 casos de fiebre tifoidea y paratifoidea -patolog\u00eda causada por bacterias del g\u00e9nero salmonella- acumulando 109 notificaciones confirmadas desde el inicio de 2023.<\/p>\n\n\n\n<p>La distribuci\u00f3n de casos en esta semana es la siguiente:<\/p>\n\n\n\n<p>\u00b7Salta: 34<\/p>\n\n\n\n<p>\u00b7Cerrillos: 3<\/p>\n\n\n\n<p>\u00b7Campo Quijano: 2<\/p>\n\n\n\n<p>\u00b7El Carril: 1<\/p>\n\n\n\n<p>\u00b7La Merced: 1<\/p>\n\n\n\n<p>\u00b7Rosario de Lerma: 1<\/p>\n\n\n\n<p>Tambi\u00e9n se confirm\u00f3 el diagn\u00f3stico de botulismo del lactante, en una ni\u00f1a reci\u00e9n nacida (27 d\u00edas), internada en el hospital Materno Infantil.<\/p>\n\n\n\n<p>El director general de Coordinaci\u00f3n Epidemiol\u00f3gica, Francisco Garc\u00eda Campos, dijo que \u201cdesde el Laboratorio de Microbiolog\u00eda de la Universidad Nacional de Cuyo, en Mendoza, confirmaron la presencia de botulismo del lactante en la muestra enviada. El paciente contin\u00faa internado, con evoluci\u00f3n favorable, recibiendo tratamiento espec\u00edfico\u201d.<\/p>\n\n\n\n<p>Enfermedades zoon\u00f3ticas<\/p>\n\n\n\n<p>En la segunda semana de enero se registraron 23 mordeduras de perros, lo que a priori se califica como accidente potencialmente r\u00e1bico (APR).<\/p>\n\n\n\n<p>&nbsp;De ellos, nueve fueron notificados en el departamento Capital, seis en San Mart\u00edn, seis en Or\u00e1n y dos en Anta.<\/p>\n\n\n\n<p>&nbsp;Adem\u00e1s, se registraron 20 casos de picadura de alacr\u00e1n (alacranismo), de los cuales 15 pertenecen al departamento Capital, dos a General G\u00fcemes, dos a Anta y uno a La Caldera.<\/p>\n\n\n\n<p>Tambi\u00e9n, se notificaron tres picaduras de serpientes (ofidismo). Con Yarar\u00e1 fueron dos los casos registrados, uno en Or\u00e1n y otro en Rosario de Lerma. Asimismo, se confirm\u00f3 un accidente of\u00eddico con una Cascabel, en Or\u00e1n.<\/p>\n\n\n\n<p>Por \u00faltimo, en la semana epidemiol\u00f3gica 2, se confirm\u00f3 un caso de leishmaniasis cut\u00e1nea.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Direcci\u00f3n General de Coordinaci\u00f3n Epidemiol\u00f3gica del Ministerio de Salud P\u00fablica, dio a conocer un informe sobre la segunda semana epidemiol\u00f3gica, comprendida entre el 8 y el 14 de enero, en el cual se incluyen los siguientes datos: En la semana epidemiol\u00f3gica 2 (SE2), se notificaron 231 casos de COVID-19, de los cuales 121 corresponden [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":40204,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[65],"tags":[],"class_list":{"0":"post-51590","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-coronavirus"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/51590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=51590"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/51590\/revisions"}],"predecessor-version":[{"id":51591,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/51590\/revisions\/51591"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/40204"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=51590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=51590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=51590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}