{"id":51626,"date":"2023-01-17T14:37:41","date_gmt":"2023-01-17T17:37:41","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=51626"},"modified":"2023-01-17T14:37:58","modified_gmt":"2023-01-17T17:37:58","slug":"multitudinaria-marcha-contra-edesa-y-continua-el-acampe-en-oran","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2023\/01\/17\/multitudinaria-marcha-contra-edesa-y-continua-el-acampe-en-oran\/","title":{"rendered":"Multitudinaria marcha contra EDESA y contin\u00faa el acampe en Or\u00e1n"},"content":{"rendered":"\n<p>Mientras el gobernador S\u00e1enz firmaba el decreto de necesidad y urgencia por el conflicto con Edesa, los vecinos de la ciudad de Or\u00e1n realizaban una multitudinaria caravana en repudio al servicio y los excesivos aumentos.<\/p>\n\n\n\n<p>Hoy contin\u00faan apostados afuera de la empresa y definir\u00e1n los pasos a seguir en las pr\u00f3ximas horas.<\/p>\n\n\n\n<p>En las redes sociales se observa un rechazo a la decisi\u00f3n del mandatario salte\u00f1o de sostener por 6 meses los valores en las facturas. Consideran que ya en noviembre, mes de referencia, hab\u00eda aumentos importantes y desde marzo baja el consumo por cuestiones clim\u00e1ticas por lo que inevitablemente tambi\u00e9n deber\u00edan bajar los precios que se cobran por el servicio.<\/p>\n\n\n\n<p>Norte Ya<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mientras el gobernador S\u00e1enz firmaba el decreto de necesidad y urgencia por el conflicto con Edesa, los vecinos de la ciudad de Or\u00e1n realizaban una multitudinaria caravana en repudio al servicio y los excesivos aumentos. Hoy contin\u00faan apostados afuera de la empresa y definir\u00e1n los pasos a seguir en las pr\u00f3ximas horas. En las redes [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":51627,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[60],"tags":[],"class_list":{"0":"post-51626","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/51626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=51626"}],"version-history":[{"count":2,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/51626\/revisions"}],"predecessor-version":[{"id":51629,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/51626\/revisions\/51629"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/51627"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=51626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=51626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=51626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}