{"id":57436,"date":"2023-05-05T16:00:54","date_gmt":"2023-05-05T19:00:54","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=57436"},"modified":"2023-05-05T16:00:55","modified_gmt":"2023-05-05T19:00:55","slug":"se-termino-la-oms-declaro-el-final-de-la-pandemia-que-dejo-un-saldo-de-casi-7-millones-de-victimas","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2023\/05\/05\/se-termino-la-oms-declaro-el-final-de-la-pandemia-que-dejo-un-saldo-de-casi-7-millones-de-victimas\/","title":{"rendered":"\u00a1Se termin\u00f3!: La OMS declar\u00f3 el final de la pandemia que dej\u00f3 un saldo de casi 7 millones de v\u00edctimas"},"content":{"rendered":"\n<p>Despu\u00e9s de tres a\u00f1os, el director de la OMS lo anunci\u00f3 en una conferencia de prensa.<\/p>\n\n\n\n<p>Comenz\u00f3 en el 2020 de menor a mayor. Primero algunas precauciones, luego algunos d\u00edas encerrados que pasaron a ser meses, m\u00e1s de mitad de a\u00f1o donde la regla dec\u00eda que todos los ciudadanos deb\u00edan permanecer en sus casas, y por \u00faltimo s\u00f3lo cuidados. Lo que parec\u00eda ser algo eterno, lleg\u00f3 a su fin este viernes por la ma\u00f1ana, luego de que la Organizaci\u00f3n Mundial de la Salud (OMS) anunciara el fin a la emergencia de salud global por el COVID-19.<\/p>\n\n\n\n<p>A fines del 2019 y principios del 2020 se comenzaron a registrar diversos casos y s\u00edntomas en Europa y en China, sin saber bien de qu\u00e9 se trataba y cu\u00e1l era el virus que se estaba expandiendo de manera tan r\u00e1pida y contundente por todo el mundo. Hasta que el 11 de febrero de 2020, la OMS declar\u00f3 que se trataba de un virus nuevo llamado Coronavirus. A partir de ah\u00ed, todo se paraliz\u00f3.<\/p>\n\n\n\n<p>En Argentina todav\u00eda no hab\u00eda pasado nada y la normalidad era total, hasta que se comenzaron a disparar diversos casos aislados en diferentes provincias, que pusieron la tensi\u00f3n a flor de piel hasta que d\u00eda a d\u00eda todo se agrav\u00f3 m\u00e1s. Lleg\u00f3 el 20 de marzo y mediante una cadena nacional, el presidente, Alberto Fern\u00e1ndez, encerr\u00f3 a todos los argentinos.<\/p>\n\n\n\n<p>Entonces, en mayo del 2023, despu\u00e9s de tres a\u00f1os, se puede confirmar que seg\u00fan determin\u00f3 la OMS, lleg\u00f3 el fin de la pandemia del Coronavirus, pero, si bien todav\u00eda se pueden registrar algunos pocos contagios, porque el virus sigue y seguir\u00e1 estando presente, ya no tendr\u00e1 la misma peligrosidad que ten\u00eda en sus principios, sino m\u00e1s bien, ser\u00e1 un virus a tratar como cualquier otra enfermedad que puede haber en el aire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de tres a\u00f1os, el director de la OMS lo anunci\u00f3 en una conferencia de prensa. Comenz\u00f3 en el 2020 de menor a mayor. Primero algunas precauciones, luego algunos d\u00edas encerrados que pasaron a ser meses, m\u00e1s de mitad de a\u00f1o donde la regla dec\u00eda que todos los ciudadanos deb\u00edan permanecer en sus casas, y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":57437,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[65],"tags":[],"class_list":{"0":"post-57436","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-coronavirus"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/57436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=57436"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/57436\/revisions"}],"predecessor-version":[{"id":57438,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/57436\/revisions\/57438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/57437"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=57436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=57436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=57436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}