{"id":57439,"date":"2023-05-05T16:10:05","date_gmt":"2023-05-05T19:10:05","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=57439"},"modified":"2023-05-05T16:10:07","modified_gmt":"2023-05-05T19:10:07","slug":"secuestran-en-tucuman-121-cubiertas-de-contrabando-en-un-omnibus-que-partio-de-oran","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2023\/05\/05\/secuestran-en-tucuman-121-cubiertas-de-contrabando-en-un-omnibus-que-partio-de-oran\/","title":{"rendered":"Secuestran en Tucum\u00e1n 121 cubiertas de contrabando en un \u00f3mnibus que parti\u00f3 de Or\u00e1n"},"content":{"rendered":"\n<p>En la localidad tucumana de Siete de Abril, se trasladaban 104 neum\u00e1ticos en un \u00f3mnibus hacia Santa Fe.<\/p>\n\n\n\n<p>En la ma\u00f1ana de ayer, integrantes dependientes del Escuadr\u00f3n 55 \u201cTucum\u00e1n\u201d controlaron un transporte de pasajeros que circulaba desde la ciudad salte\u00f1a de Or\u00e1n hacia la ciudad de Reconquista, provincia de Santa Fe.<\/p>\n\n\n\n<p>El hecho ocurri\u00f3 a la altura del kil\u00f3metro 986 de la Ruta Nacional N\u00b0 34, cuando los gendarmes incautaron 104 cubiertas en infracci\u00f3n a la Ley 22.415 \u201cC\u00f3digo Aduanero\u201d, por disposici\u00f3n del Juzgado Federal N\u00b0 2 de Tucum\u00e1n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la localidad tucumana de Siete de Abril, se trasladaban 104 neum\u00e1ticos en un \u00f3mnibus hacia Santa Fe. En la ma\u00f1ana de ayer, integrantes dependientes del Escuadr\u00f3n 55 \u201cTucum\u00e1n\u201d controlaron un transporte de pasajeros que circulaba desde la ciudad salte\u00f1a de Or\u00e1n hacia la ciudad de Reconquista, provincia de Santa Fe. El hecho ocurri\u00f3 a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":57440,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[63],"tags":[],"class_list":{"0":"post-57439","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policiales"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/57439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=57439"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/57439\/revisions"}],"predecessor-version":[{"id":57441,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/57439\/revisions\/57441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/57440"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=57439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=57439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=57439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}