{"id":57467,"date":"2023-05-07T23:09:21","date_gmt":"2023-05-08T02:09:21","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=57467"},"modified":"2023-05-07T23:09:23","modified_gmt":"2023-05-08T02:09:23","slug":"elecciones-la-rioja-2023-quintela-se-asegura-su-reeleccion-y-el-candidato-de-milei-quedaba-en-el-tercer-puesto","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2023\/05\/07\/elecciones-la-rioja-2023-quintela-se-asegura-su-reeleccion-y-el-candidato-de-milei-quedaba-en-el-tercer-puesto\/","title":{"rendered":"Elecciones La Rioja 2023: Quintela se asegura su reelecci\u00f3n y el candidato de Milei quedaba en el tercer puesto"},"content":{"rendered":"\n<p>Se vot\u00f3 para gobernador, legisladores, intendentes y convencionales constituyentes. Los primeros le dan una diferencia al Gobernador, quien brindar\u00e1 una conferencia de prensa.<\/p>\n\n\n\n<p>El gobernador de La Rioja, Ricardo Quintela (Frente de Todos), lograba esta noche una ventaja de m\u00e1s de 14 puntos sobre su rival de Juntos por el Cambio, Felipe Alvarez, cuando estaba escrutado algo m\u00e1s del 10% de los votos. Por ello, desde el entorno del candidato del Frente de Todos se inform\u00f3 que brindar\u00e1 una conferencia de prensa desde su residencia a las 22.30.<\/p>\n\n\n\n<p>En tanto, en el escrutinio, Mart\u00edn Menem, del sector libertario de Javier Milei, quedaba alejado en el tercer lugar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se vot\u00f3 para gobernador, legisladores, intendentes y convencionales constituyentes. Los primeros le dan una diferencia al Gobernador, quien brindar\u00e1 una conferencia de prensa. El gobernador de La Rioja, Ricardo Quintela (Frente de Todos), lograba esta noche una ventaja de m\u00e1s de 14 puntos sobre su rival de Juntos por el Cambio, Felipe Alvarez, cuando estaba [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":57468,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[59],"tags":[],"class_list":{"0":"post-57467","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/57467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=57467"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/57467\/revisions"}],"predecessor-version":[{"id":57469,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/57467\/revisions\/57469"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/57468"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=57467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=57467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=57467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}