{"id":57606,"date":"2023-05-09T18:22:04","date_gmt":"2023-05-09T21:22:04","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=57606"},"modified":"2023-05-09T18:22:06","modified_gmt":"2023-05-09T21:22:06","slug":"declararon-a-donald-trump-responsable-de-abuso-sexual","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2023\/05\/09\/declararon-a-donald-trump-responsable-de-abuso-sexual\/","title":{"rendered":"Declararon a Donald Trump responsable de &#8220;abuso sexual&#8221;"},"content":{"rendered":"\n<p>Fue en el juicio en el que se dirimi\u00f3 la denuncia de la escritora E. Jean Carrol, quien dijo que el ex presidente la atac\u00f3 entre 1995 y 1996. Lo condenaron a indemnizarla por cinco millones de d\u00f3lares.<\/p>\n\n\n\n<p>El ex presidente de los Estados Unidos, Donald Trump&nbsp;&nbsp; abus\u00f3 sexualmente de la escritora E. Jean Carroll en la d\u00e9cada de 1990 y luego la difam\u00f3 tach\u00e1ndola de mentirosa, decidieron jurados este martes, por lo que le otorgaron 5 millones de d\u00f3lares por da\u00f1os y perjuicios.<\/p>\n\n\n\n<p>El expresidente estadounidense, en campa\u00f1a para volver a ocupar la Casa Blanca en 2024, apelar\u00e1, dijo su portavoz Steven Cheung. Trump no tendr\u00e1 que pagar mientras el caso est\u00e9 en apelaci\u00f3n.<\/p>\n\n\n\n<p>Carroll, de 79 a\u00f1os, testific\u00f3 durante el juicio civil que Trump, de 76, la viol\u00f3 en un probador de los grandes almacenes Bergdorf Goodman en Manhattan en 1995 o 1996, y luego da\u00f1\u00f3 su reputaci\u00f3n al escribir en una publicaci\u00f3n de octubre de 2022 en su plataforma Truth Social que sus afirmaciones eran una &#8220;completa estafa&#8221;, &#8220;un enga\u00f1o&#8221; y &#8220;una mentira&#8221;.<\/p>\n\n\n\n<p>Carroll se tom\u00f3 de la mano con sus abogados mientras se le\u00eda el veredicto. Sali\u00f3 del tribunal con su abogada Roberta Kaplan, sonriente y con gafas de sol, y entr\u00f3 en un autom\u00f3vil sin hablar con los periodistas.<\/p>\n\n\n\n<p>El jurado de nueve miembros del tribunal federal de Manhattan concedi\u00f3 unos 5 millones de d\u00f3lares en da\u00f1os compensatorios y punitivos a Carroll.<\/p>\n\n\n\n<p>La deliberaci\u00f3n, que dur\u00f3 algo menos de tres horas, rechaz\u00f3 la versi\u00f3n de Trump, que neg\u00f3 haber agredido a Carroll, y fall\u00f3 en favor de ella. Para declararlo responsable, el jurado, compuesto por seis hombres y tres mujeres, deb\u00eda alcanzar un veredicto un\u00e1nime.<\/p>\n\n\n\n<p>Presidente de 2017 a 2021, Trump es el favorito en las encuestas de opini\u00f3n para ser el candidato presidencial republicano y ha demostrado una extra\u00f1a habilidad para capear controversias que podr\u00edan hundir a otros pol\u00edticos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fue en el juicio en el que se dirimi\u00f3 la denuncia de la escritora E. Jean Carrol, quien dijo que el ex presidente la atac\u00f3 entre 1995 y 1996. Lo condenaron a indemnizarla por cinco millones de d\u00f3lares. El ex presidente de los Estados Unidos, Donald Trump&nbsp;&nbsp; abus\u00f3 sexualmente de la escritora E. Jean Carroll [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":15255,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[59],"tags":[],"class_list":{"0":"post-57606","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/57606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=57606"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/57606\/revisions"}],"predecessor-version":[{"id":57607,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/57606\/revisions\/57607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/15255"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=57606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=57606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=57606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}