{"id":57938,"date":"2023-05-18T11:02:02","date_gmt":"2023-05-18T14:02:02","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=57938"},"modified":"2023-05-18T11:02:04","modified_gmt":"2023-05-18T14:02:04","slug":"solicitan-juicio-para-el-ex-intendente-de-oran-marcelo-lara-gros-y-para-4-exfuncionarios-de-su-gestion","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2023\/05\/18\/solicitan-juicio-para-el-ex-intendente-de-oran-marcelo-lara-gros-y-para-4-exfuncionarios-de-su-gestion\/","title":{"rendered":"Solicitan juicio para el ex intendente de Oran, Marcelo Lara Gros y para 4 exfuncionarios de su gesti\u00f3n"},"content":{"rendered":"\n<p>La fiscal penal 3 de Or\u00e1n, con competencia en Delitos Econ\u00f3micos Complejos, M\u00f3nica Viazzi, requiri\u00f3 juicio ante el Juzgado de Garant\u00edas 2 de ese distrito, para Marcelo Lara Gros como autor de los delitos de incumplimiento de los deberes de funcionario p\u00fablico (dos hechos) en concurso real con falsedad ideol\u00f3gica.<\/p>\n\n\n\n<p>Para Javier Arnaldo Tartalo, quien se desempe\u00f1aba como secretario de Gobierno, como part\u00edcipe necesario de los delitos de incumplimiento de los deberes de funcionario p\u00fablico y falsedad ideol\u00f3gica.<\/p>\n\n\n\n<p>Para Sebasti\u00e1n Ra\u00fal Gottero, como secretario de Hacienda y Planificaci\u00f3n y Jefe de Gabinete; para Luis Eduardo Pintado como Subsecretario de Hacienda; para Claudio Francisco Tosoni Garc\u00eda como Gerente de Compras de la Municipalidad como autores del delito de incumplimiento de los deberes de funcionario p\u00fablico.<\/p>\n\n\n\n<p>El primer hecho investigado ocurri\u00f3 en mayo de 2018, cuando se denunci\u00f3 que el entonces Jefe Comunal se hab\u00eda ausentado del pa\u00eds el d\u00eda 17 de ese mes y que reci\u00e9n una semana despu\u00e9s, ingres\u00f3 por la Mesa de Entradas del Concejo Deliberante, una notificaci\u00f3n de que se ausentar\u00eda desde el 26 de mayo hasta el 2 de junio.<\/p>\n\n\n\n<p>En la acusaci\u00f3n se considera que tanto Lara Gros como quien fuera su secretario de Gobierno, teniendo conocimiento de tal situaci\u00f3n, no la hicieron saber, avalando la irregularidad y asumiendo funciones que no le correspond\u00edan en funci\u00f3n de lo establecido en el art 75 de la Carta Org\u00e1nica de la ciudad Oran ley 6571.<\/p>\n\n\n\n<p>El segundo hecho investigado ocurri\u00f3 cuando bajo la gesti\u00f3n del entonces Intendente y con el aval de sus funcionarios, se ejecut\u00f3 la obra de construcci\u00f3n de una rotonda en el acceso Sur de la ciudad, sin informar el monto destinado, ni los procedimientos empleados, al Concejo Deliberante. Se eval\u00faa adem\u00e1s que la obra, no se encontraba en el plan de obras ni el presupuesto de ese a\u00f1o, incumpliendo las leyes que rigen la materia.<\/p>\n\n\n\n<p>En el requerimiento, la fiscal Viazzi expone detalladamente todas las medidas probatorias producidas durante la investigaci\u00f3n y que constituyen los elementos de convicci\u00f3n suficientes para solicitar que la causa sea llevada juicio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La fiscal penal 3 de Or\u00e1n, con competencia en Delitos Econ\u00f3micos Complejos, M\u00f3nica Viazzi, requiri\u00f3 juicio ante el Juzgado de Garant\u00edas 2 de ese distrito, para Marcelo Lara Gros como autor de los delitos de incumplimiento de los deberes de funcionario p\u00fablico (dos hechos) en concurso real con falsedad ideol\u00f3gica. Para Javier Arnaldo Tartalo, quien [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":57939,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[63],"tags":[],"class_list":{"0":"post-57938","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policiales"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/57938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=57938"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/57938\/revisions"}],"predecessor-version":[{"id":57940,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/57938\/revisions\/57940"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/57939"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=57938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=57938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=57938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}