{"id":62665,"date":"2023-08-10T12:38:48","date_gmt":"2023-08-10T15:38:48","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=62665"},"modified":"2023-08-10T12:39:12","modified_gmt":"2023-08-10T15:39:12","slug":"hasta-cuando-massa-dolar-blue-pego-otro-salto-y-en-salta-se-venda-a-620","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2023\/08\/10\/hasta-cuando-massa-dolar-blue-pego-otro-salto-y-en-salta-se-venda-a-620\/","title":{"rendered":"\u00a1Hasta cuando Massa! D\u00f3lar blue peg\u00f3 otro salto y en Salta se vende a $ 620"},"content":{"rendered":"\n<p>El d\u00f3lar blue sube $8 este jueves 10 de agosto, cotiza a $603 para la compra y $608 para la venta en la City porte\u00f1a mientras que en Salta opera en 610 para la compra y 620 para la venta. La brecha con el d\u00f3lar mayorista se ubica en 112,40%.<\/p>\n\n\n\n<p>En tanto, el d\u00f3lar oficial (sin impuestos) aumenta 50 centavos y opera a $282,50 para la compra y $295,50 para la venta en las pantallas del Banco de la Naci\u00f3n Argentina (BNA).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El d\u00f3lar blue sube $8 este jueves 10 de agosto, cotiza a $603 para la compra y $608 para la venta en la City porte\u00f1a mientras que en Salta opera en 610 para la compra y 620 para la venta. La brecha con el d\u00f3lar mayorista se ubica en 112,40%. En tanto, el d\u00f3lar oficial [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":30275,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[60],"tags":[],"class_list":{"0":"post-62665","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/62665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=62665"}],"version-history":[{"count":3,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/62665\/revisions"}],"predecessor-version":[{"id":62668,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/62665\/revisions\/62668"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/30275"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=62665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=62665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=62665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}