{"id":69397,"date":"2023-12-07T13:28:07","date_gmt":"2023-12-07T16:28:07","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=69397"},"modified":"2023-12-07T13:28:10","modified_gmt":"2023-12-07T16:28:10","slug":"inauguraron-el-tren-solar-de-jujuy-habra-cuatro-tipos-de-tarifas-y-proyectan-comprar-mas-duplas","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2023\/12\/07\/inauguraron-el-tren-solar-de-jujuy-habra-cuatro-tipos-de-tarifas-y-proyectan-comprar-mas-duplas\/","title":{"rendered":"Inauguraron el tren solar de Jujuy: habr\u00e1 cuatro tipos de tarifas y proyectan comprar m\u00e1s duplas"},"content":{"rendered":"\n<p>Durante la inauguraci\u00f3n se anunci\u00f3 la tarifa diferenciada que habr\u00e1 para turistas y locales. Adem\u00e1s, detallaron la adquisici\u00f3n de m\u00e1s duplas para la Quebrada.<\/p>\n\n\n\n<p>Pasado el mediod\u00eda de este jueves qued\u00f3 inaugurado oficialmente el primer tramo del Tren Solar de la Quebrada con el viaje del gobernador de Jujuy, Gerardo Morales, el gobernador electo Carlos Sadir, autoridades de las empresas chinas que estuvieron a cargo de concretar el proyecto, entre otras autoridades provinciales.<\/p>\n\n\n\n<p>Previo al viaje oficial, Morales brind\u00f3 un discurso donde explic\u00f3 la importancia de concretar el proyecto del primer tren solar en la provincia y lo que significa para los pueblos de la Quebrada.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"575\" height=\"324\" src=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2023\/12\/image-87.png\" alt=\"\" class=\"wp-image-69399\" style=\"width:914px;height:auto\" srcset=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2023\/12\/image-87.png 575w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2023\/12\/image-87-300x169.png 300w\" sizes=\"auto, (max-width: 575px) 100vw, 575px\" \/><\/figure>\n\n\n\n<p>\u201cEstamos muy contentos cumpliendo con este sue\u00f1o. Nos levantamos y nos ca\u00edmos tantas veces en el camino, pero sab\u00edamos que hab\u00eda que recuperar este tramo que era muy importante\u201d, indic\u00f3 Morales. Luego agreg\u00f3: \u201cVamos por parte, el primer tramo es el de Volc\u00e1n a Tilcara, pero despu\u00e9s hay que seguir hasta Humahuaca, La Quiaca y queda el tramo m\u00e1s dif\u00edcil que es la Cuesta de B\u00e1rcena\u201d.<\/p>\n\n\n\n<p>M\u00e1s adelante el gobernador que ya termina su mandato, precis\u00f3: \u201cEste proyecto tiene un par de meses de prueba. A Tilcara todav\u00eda nos faltan unos pocos kil\u00f3metros de v\u00edas, pero vamos a estar all\u00ed trabajando r\u00e1pidamente\u201d.<\/p>\n\n\n\n<p>Tarifa diferenciada<\/p>\n\n\n\n<p>Si bien d\u00edas previos se anunci\u00f3 la suma total de 40.000 pesos para adquirir el pasaje del tren, Morales precis\u00f3 que se aplicar\u00e1n tarifas diferenciadas tanto para turistas como as\u00ed tambi\u00e9n locales.<\/p>\n\n\n\n<p>En medio del discurso de inauguraci\u00f3n, Morales indic\u00f3 que habr\u00e1 dos tarifas turistas: una para turistas extranjeros y otro para turistas argentinos. Mientras que por otro lado habr\u00e1 una tarifa para turistas de la provincia y otra para la gente local de la Quebrada.<\/p>\n\n\n\n<p>Adquisici\u00f3n de m\u00e1s duplas<\/p>\n\n\n\n<p>En este sentido Morales detall\u00f3 que se prev\u00e9 adquirir 7 duplas m\u00e1s para la provincia de Jujuy: \u201cDos estar\u00e1n quedar\u00e1n en el recorrido en la Quebrada y las otras cinco estar\u00e1n destinadas al proyecto que prev\u00e9 tener un tren que realizar\u00e1 el recorrido de la capital juje\u00f1a hacia el aeropuerto\u201d.<\/p>\n\n\n\n<p>Finalmente el mandatario precis\u00f3 que se est\u00e1 gestionando tener un tren de cercan\u00eda para el pueblo y el mismo ir\u00e1 de Volc\u00e1n a Tilcara.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante la inauguraci\u00f3n se anunci\u00f3 la tarifa diferenciada que habr\u00e1 para turistas y locales. Adem\u00e1s, detallaron la adquisici\u00f3n de m\u00e1s duplas para la Quebrada. Pasado el mediod\u00eda de este jueves qued\u00f3 inaugurado oficialmente el primer tramo del Tren Solar de la Quebrada con el viaje del gobernador de Jujuy, Gerardo Morales, el gobernador electo Carlos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":69398,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[73],"tags":[],"class_list":{"0":"post-69397","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-general"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/69397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=69397"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/69397\/revisions"}],"predecessor-version":[{"id":69400,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/69397\/revisions\/69400"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/69398"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=69397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=69397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=69397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}