{"id":71391,"date":"2024-01-16T17:25:39","date_gmt":"2024-01-16T20:25:39","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=71391"},"modified":"2024-01-16T17:25:39","modified_gmt":"2024-01-16T20:25:39","slug":"secuestran-en-aunor-dos-autos-por-transporte-ilegal-de-pasajeros","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2024\/01\/16\/secuestran-en-aunor-dos-autos-por-transporte-ilegal-de-pasajeros\/","title":{"rendered":"Secuestran en Aunor dos autos por transporte ilegal de pasajeros"},"content":{"rendered":"\n<p>En el marco del trabajo conjunto que lleva adelante Polic\u00eda de Salta con la Autoridad Metropolitana del Transporte, efectivos de la Direcci\u00f3n General de la vial que realizaban control vehicular sobre Ruta Nacional N\u00b0 9 constataron que dos conductores transportaban pasajeros sin habilitaci\u00f3n.<\/p>\n\n\n\n<p>La primera intervenci\u00f3n ocurri\u00f3 pasadas las 9 horas cuando al controlar la documentaci\u00f3n del conductor de un taxi, detectaron que transportaba pasajeros sin la autorizaci\u00f3n correspondiente por parte del organismo competente.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"763\" height=\"461\" src=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/01\/taxi-trucho.jpg\" alt=\"\" class=\"wp-image-71393\" style=\"width:1068px;height:auto\" srcset=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/01\/taxi-trucho.jpg 763w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/01\/taxi-trucho-300x181.jpg 300w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/01\/taxi-trucho-696x421.jpg 696w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/01\/taxi-trucho-695x420.jpg 695w\" sizes=\"auto, (max-width: 763px) 100vw, 763px\" \/><\/figure>\n\n\n\n<p>M\u00e1s tarde, los efectivos constataron id\u00e9ntica situaci\u00f3n con otro conductor que proven\u00eda de la Provincia de Jujuy, realizando trasporte de dos pasajeros careciendo con la documentaci\u00f3n habilitante.<\/p>\n\n\n\n<p>En ambos casos, los conductores fueron sancionados en el marco de la Ley Provincial de Transporte por ejercer la citada actividad en forma ilegal y los rodados quedaron retenidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco del trabajo conjunto que lleva adelante Polic\u00eda de Salta con la Autoridad Metropolitana del Transporte, efectivos de la Direcci\u00f3n General de la vial que realizaban control vehicular sobre Ruta Nacional N\u00b0 9 constataron que dos conductores transportaban pasajeros sin habilitaci\u00f3n. La primera intervenci\u00f3n ocurri\u00f3 pasadas las 9 horas cuando al controlar la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":71392,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[63],"tags":[],"class_list":{"0":"post-71391","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policiales"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/71391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=71391"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/71391\/revisions"}],"predecessor-version":[{"id":71394,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/71391\/revisions\/71394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/71392"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=71391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=71391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=71391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}