{"id":72108,"date":"2024-01-29T12:10:23","date_gmt":"2024-01-29T15:10:23","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=72108"},"modified":"2024-01-29T12:10:24","modified_gmt":"2024-01-29T15:10:24","slug":"los-casos-de-dengue-suben-antes-de-lo-esperado-salta-entre-las-provincias-con-circulacion-autoctona","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2024\/01\/29\/los-casos-de-dengue-suben-antes-de-lo-esperado-salta-entre-las-provincias-con-circulacion-autoctona\/","title":{"rendered":"Los casos de dengue suben antes de lo esperado: Salta entre las provincias con circulaci\u00f3n aut\u00f3ctona"},"content":{"rendered":"\n<p>La enfermedad transmitida por el mosquito Aedes aegypti ya caus\u00f3 una epidemia en Argentina en 2023. Los contagios suelen incrementarse entre febrero y marzo, pero este a\u00f1o se anticiparon. Cu\u00e1les son las provincias con circulaci\u00f3n aut\u00f3ctona.<\/p>\n\n\n\n<p>El dengue hab\u00eda sido erradicado de la Argentina a mediados del siglo pasado gracias a programas de control del mosquito Aedes aegypti, que es el vector de trasmisi\u00f3n de la infecci\u00f3n. Pero en 1997 se detect\u00f3 nuevamente la circulaci\u00f3n aut\u00f3ctona del virus que causa el dengue en Salta y luego avanz\u00f3 la reemergencia por el pa\u00eds. Desde entonces hubo aumento de casos entre los meses de febrero y mayo, incluyendo tres grandes epidemias, en 2009, 2016 y 2020.<\/p>\n\n\n\n<p>Pero desde el a\u00f1o pasado, el dengue est\u00e1 siguiendo una tendencia diferente: est\u00e1 dejando de ser estacional. Durante todo 2023 hubo reportes de casos incluso en invierno.<\/p>\n\n\n\n<p>En el primer mes de 2024, ya se ha notificado una cantidad in\u00e9dita de personas con la infecci\u00f3n para la \u00e9poca del a\u00f1o. Desde el Ministerio de Salud de la Naci\u00f3n informaron a Infobae que hubo 11.800 casos reportados de dengue durante las primeras tres semanas de enero.<\/p>\n\n\n\n<p>En las dos primeras fueron entre 3.600 y 4.800 casos por semana, y en la tercera m\u00e1s de 3.000.<\/p>\n\n\n\n<p>Otra cuesti\u00f3n llamativa es que el brote epid\u00e9mico se est\u00e1 produciendo en 11 de las 24 jurisdicciones del pa\u00eds. De acuerdo con los epidemi\u00f3logos de la cartera de Salud, esas 11 jurisdicciones han notificado 5 o m\u00e1s casos sin antecedente de viaje. Adem\u00e1s, todas las jurisdicciones han presentado casos importados.<\/p>\n\n\n\n<p>Las jurisdicciones con circulaci\u00f3n aut\u00f3ctona de dengue hoy son Chaco, Formosa, Misiones, Corrientes, Buenos Aires, Ciudad de Buenos Aires, C\u00f3rdoba, Santa Fe, Entre R\u00edos, Santiago del Estero, Tucum\u00e1n, Catamarca, Jujuy, Salta, y San Luis. Las provincias de Mendoza, La Pampa y Neuqu\u00e9n notificaron casos que est\u00e1n en investigaci\u00f3n en las \u00faltimas 4 semanas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La enfermedad transmitida por el mosquito Aedes aegypti ya caus\u00f3 una epidemia en Argentina en 2023. Los contagios suelen incrementarse entre febrero y marzo, pero este a\u00f1o se anticiparon. Cu\u00e1les son las provincias con circulaci\u00f3n aut\u00f3ctona. El dengue hab\u00eda sido erradicado de la Argentina a mediados del siglo pasado gracias a programas de control del [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":56338,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[73],"tags":[],"class_list":{"0":"post-72108","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-general"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/72108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=72108"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/72108\/revisions"}],"predecessor-version":[{"id":72109,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/72108\/revisions\/72109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/56338"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=72108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=72108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=72108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}