{"id":72119,"date":"2024-01-29T13:53:32","date_gmt":"2024-01-29T16:53:32","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=72119"},"modified":"2024-01-29T13:53:32","modified_gmt":"2024-01-29T16:53:32","slug":"incautan-mas-de-17-kilos-de-cocaina-en-un-camion-boliviano-de-carga-peligrosa","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2024\/01\/29\/incautan-mas-de-17-kilos-de-cocaina-en-un-camion-boliviano-de-carga-peligrosa\/","title":{"rendered":"Incautan m\u00e1s de 17 kilos de coca\u00edna en un cami\u00f3n boliviano de carga peligrosa"},"content":{"rendered":"\n<p>Integrantes de la Secci\u00f3n \u201cControl de Ruta 34\u201d, dependientes del Escuadr\u00f3n 54 \u201cAguaray\u201d, realizaban un operativo de prevenci\u00f3n emplazado sobre el kil\u00f3metro 1.466 del mencionado corredor, cuando inspeccionaron a un cami\u00f3n de carga peligrosa de bandera boliviana.<\/p>\n\n\n\n<p>Al momento de la requisa en el sector de la cabina del rodado, los funcionarios detectaron la presencia de dos mochilas que conten\u00edan 17 paquetes rectangulares con una sustancia blancuzca en su interior.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"537\" height=\"600\" src=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/01\/camion-boliviano-1.jpg\" alt=\"\" class=\"wp-image-72122\" style=\"width:1068px;height:auto\" srcset=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/01\/camion-boliviano-1.jpg 537w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/01\/camion-boliviano-1-269x300.jpg 269w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/01\/camion-boliviano-1-300x335.jpg 300w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/01\/camion-boliviano-1-376x420.jpg 376w\" sizes=\"auto, (max-width: 537px) 100vw, 537px\" \/><\/figure>\n\n\n\n<p>Personal de Criminal\u00edstica y Estudios Forenses realizaron las pruebas de campo Narcotest sobre la sustancia hallada, que arrojaron resultado positivo para \u201cclorhidrato de coca\u00edna\u201d con un peso total de 17 kilos 616 gramos.<\/p>\n\n\n\n<p>La coca\u00edna llevaba impresa un \u201cDelf\u00edn\u201d tal como se conoc\u00eda a la banda narco de los hermanos Castedo hoy condenados y en prisi\u00f3n, pero la droga sigue circulando con el mismo sello identificatorio.<\/p>\n\n\n\n<p>Intervino la Fiscal\u00eda Federal Descentralizada de Tartagal, que orient\u00f3 la detenci\u00f3n del ciudadano involucrado, la incautaci\u00f3n de la sustancia, y del rodado, en infracci\u00f3n a la Ley 23.737 de \u201cEstupefacientes\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Integrantes de la Secci\u00f3n \u201cControl de Ruta 34\u201d, dependientes del Escuadr\u00f3n 54 \u201cAguaray\u201d, realizaban un operativo de prevenci\u00f3n emplazado sobre el kil\u00f3metro 1.466 del mencionado corredor, cuando inspeccionaron a un cami\u00f3n de carga peligrosa de bandera boliviana. Al momento de la requisa en el sector de la cabina del rodado, los funcionarios detectaron la presencia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":72121,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[63],"tags":[],"class_list":{"0":"post-72119","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policiales"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/72119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=72119"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/72119\/revisions"}],"predecessor-version":[{"id":72123,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/72119\/revisions\/72123"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/72121"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=72119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=72119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=72119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}