{"id":7360,"date":"2020-10-02T09:49:03","date_gmt":"2020-10-02T12:49:03","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=7360"},"modified":"2020-10-02T09:49:04","modified_gmt":"2020-10-02T12:49:04","slug":"ahora-3-empleados-del-pami-en-la-mira-de-la-justicia-por-el-cobro-del-ife","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2020\/10\/02\/ahora-3-empleados-del-pami-en-la-mira-de-la-justicia-por-el-cobro-del-ife\/","title":{"rendered":"Ahora 3 empleados del PAMI en la mira de la Justicia por el cobro del IFE"},"content":{"rendered":"\n<p>La Justicia Federal remiti\u00f3 un oficio a la oficina del PAMI en Salta solicitando informaci\u00f3n sobre tres empleados que percibieron el IFE en el marco de la investigaci\u00f3n que se sigue por el cobro irregular del Ingreso familiar de emergencia.<\/p>\n\n\n\n<p>Se trata de Javier Navarreta, Emilia Fabiana Ju\u00e1rez y Viviana Beatriz Fern\u00e1ndez. La Justicia quiera saber desde cuando se desempe\u00f1an en ese organismo y cu\u00e1les son sus cargos, debido a que estar\u00edan acusados por los delitos de defraudaci\u00f3n a la administraci\u00f3n p\u00fablica e incumplimiento de los deberes de funcionarios p\u00fablicos.<\/p>\n\n\n\n<p>Tambi\u00e9n continua la investigaci\u00f3n de los otros implicados que ser\u00edan concejales y funcionarios que tambi\u00e9n percibieron el IFE.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Justicia Federal remiti\u00f3 un oficio a la oficina del PAMI en Salta solicitando informaci\u00f3n sobre tres empleados que percibieron el IFE en el marco de la investigaci\u00f3n que se sigue por el cobro irregular del Ingreso familiar de emergencia. Se trata de Javier Navarreta, Emilia Fabiana Ju\u00e1rez y Viviana Beatriz Fern\u00e1ndez. La Justicia quiera [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7361,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[73],"tags":[],"class_list":{"0":"post-7360","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-general"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/7360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=7360"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/7360\/revisions"}],"predecessor-version":[{"id":7362,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/7360\/revisions\/7362"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/7361"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=7360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=7360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=7360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}