{"id":74633,"date":"2024-03-13T11:07:36","date_gmt":"2024-03-13T14:07:36","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=74633"},"modified":"2024-03-13T11:07:37","modified_gmt":"2024-03-13T14:07:37","slug":"3-funcionarios-municipales-de-humahuaca-detenidos-por-atropellar-matar-a-un-joven-y-darse-a-la-fuga","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2024\/03\/13\/3-funcionarios-municipales-de-humahuaca-detenidos-por-atropellar-matar-a-un-joven-y-darse-a-la-fuga\/","title":{"rendered":"3 funcionarios municipales de Humahuaca detenidos por atropellar, matar a un joven y darse a la fuga"},"content":{"rendered":"\n<p>El joven Emanuel V\u00e1squez perdi\u00f3 la vida en un lamentable siniestro vial en Ruta 9, donde fue atropellado por un veh\u00edculo que se dio a la fuga. Su familia movi\u00f3 cielo y tierra buscando pruebas y finalmente se supo que el veh\u00edculo involucrado pertenec\u00eda a la Municipalidad humahuaque\u00f1a y hay tres funcionarios detenidos e imputados.<\/p>\n\n\n\n<p>Desde ese momento, su familia movi\u00f3 cielo y tierra para conseguir pruebas y reclamar por justicia. Desde un primer momento, por lo recabado, sosten\u00edan y tem\u00edan que se trate de un nuevo \u201ccaso Mat\u00edas Puca\u201d. Acudieron a la capital juje\u00f1a para visibilizar la situaci\u00f3n y expon\u00edan que hab\u00eda funcionarios que pretend\u00edan ocultar pruebas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"597\" src=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/03\/image-85-1024x597.png\" alt=\"\" class=\"wp-image-74636\" srcset=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/03\/image-85-1024x597.png 1024w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/03\/image-85-300x175.png 300w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/03\/image-85-768x448.png 768w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/03\/image-85-696x406.png 696w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/03\/image-85-1068x623.png 1068w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/03\/image-85-720x420.png 720w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/03\/image-85.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Tanta fue la insistencia que lograron avances de suma notoriedad en la causa y en la \u00faltima jornada se conoci\u00f3 que tres funcionarios de la Municipalidad humahuaque\u00f1a fueron detenidos e imputados.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/03\/image-84-1024x576.png\" alt=\"\" class=\"wp-image-74634\" srcset=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/03\/image-84-1024x576.png 1024w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/03\/image-84-300x169.png 300w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/03\/image-84-768x432.png 768w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/03\/image-84-696x392.png 696w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/03\/image-84-1068x601.png 1068w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/03\/image-84-747x420.png 747w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/03\/image-84.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Se trata de Alejandro Escobar, secretario de Acci\u00f3n Social quien est\u00e1 sindicado como el conductor del rodado e imputado de &#8220;homicidio culposo agravado&#8221;, mientras que Antonio R\u00edos Secretario de Gobierno y Alejandro Caz\u00f3n Secretario de Hacienda, est\u00e1n se\u00f1alados como los encubridores y c\u00f3mplices en el ocultamiento de informaci\u00f3n, imputados de &#8220;encubrimiento agravado&#8221;. Adem\u00e1s, tras una serie de allanamientos, se logr\u00f3 el secuestro de una camioneta Toyota Hilux, la cual habr\u00eda sido utilizada al momento del accidente de tr\u00e1nsito.<\/p>\n\n\n\n<p>Jujuy al Momento<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El joven Emanuel V\u00e1squez perdi\u00f3 la vida en un lamentable siniestro vial en Ruta 9, donde fue atropellado por un veh\u00edculo que se dio a la fuga. Su familia movi\u00f3 cielo y tierra buscando pruebas y finalmente se supo que el veh\u00edculo involucrado pertenec\u00eda a la Municipalidad humahuaque\u00f1a y hay tres funcionarios detenidos e imputados. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":74635,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[63],"tags":[],"class_list":{"0":"post-74633","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policiales"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/74633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=74633"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/74633\/revisions"}],"predecessor-version":[{"id":74637,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/74633\/revisions\/74637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/74635"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=74633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=74633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=74633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}