{"id":74642,"date":"2024-03-13T11:19:34","date_gmt":"2024-03-13T14:19:34","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=74642"},"modified":"2024-03-13T11:19:35","modified_gmt":"2024-03-13T14:19:35","slug":"alerta-6-de-cada-10-ninos-y-adolescentes-escolarizados-en-argentina-son-pobres","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2024\/03\/13\/alerta-6-de-cada-10-ninos-y-adolescentes-escolarizados-en-argentina-son-pobres\/","title":{"rendered":"Alerta: 6 de cada 10 ni\u00f1os y adolescentes escolarizados en Argentina son pobres"},"content":{"rendered":"\n<p>Un informe de la UCA revela el complejo panorama que atraviesan los j\u00f3venes argentinos que asisten a establecimientos educativos.<\/p>\n\n\n\n<p>El impacto de la crisis econ\u00f3mica en la Argentina cada vez se siente m\u00e1s en los ni\u00f1os y adolescentes, lo que se viene reflejando en distintos informes que alertan sobre la creciente poblaci\u00f3n juvenil que cae bajo la l\u00ednea de pobreza.<\/p>\n\n\n\n<p>Esta realidad no es ajena al \u00e1mbito educativo y as\u00ed queda demostrado en el \u00faltimo informe del Observatorio de la Deuda Social Argentina (ODSA) de la Universidad Cat\u00f3lica Argentina (UCA), que revel\u00f3 que 6 de cada 10 ni\u00f1os y adolescentes escolarizados en el pa\u00eds son pobres, es decir el 62,9%.<\/p>\n\n\n\n<p>La mayor proporci\u00f3n de este grupo la componen los alumnos de escuelas p\u00fablicas, donde la pobreza alcanza a 7 de cada 10 (71,6%).<\/p>\n\n\n\n<p>En tanto que en el caso de las escuelas privadas laicas, el porcentaje cae a 26,8%, mientras que la cifra asciende al 33,9% entre los alumnos de colegios parroquiales o religiosos. Al tener en cuenta ambos sectores de gesti\u00f3n privada, el an\u00e1lisis arroja que 3 de cada 10 alumnos de escuelas privadas (29,4%) se encuentran en situaci\u00f3n de pobreza, lo que representa cerca de 356.000 ni\u00f1os y adolescentes.<\/p>\n\n\n\n<p>El informe \u201cCaracterizaci\u00f3n de la poblaci\u00f3n de ni\u00f1os\/as y adolescentes escolarizados seg\u00fan el tipo de gesti\u00f3n educativa\u201d de la UCA, que abarca a ni\u00f1os y adolescentes entre 0 y 17 a\u00f1os que asisten a instituciones educativas, precis\u00f3 tambi\u00e9n que el 16,2% de los alumnos argentinos se encuentran en situaci\u00f3n de indigencia.<\/p>\n\n\n\n<p>La mayor\u00eda de los ni\u00f1os y adolescentes escolarizados del pa\u00eds asisten a escuelas de gesti\u00f3n estatal (72,4%), seg\u00fan datos del \u00faltimo Relevamiento Anual elaborado por el entonces Ministerio de Educaci\u00f3n de la Naci\u00f3n. De los tres niveles obligatorios (inicial, primario y secundario), el jard\u00edn de infantes es el que tiene los mayores porcentajes de matr\u00edcula en el sector de gesti\u00f3n privada.<\/p>\n\n\n\n<p>El estudio que fue publicado este lunes y corresponde al segundo semestre de 2023, supone una leve mejora con respecto a las cifras de 2022.<\/p>\n\n\n\n<p>El documento, que fue entregado a funcionarios de la Secretar\u00eda de Educaci\u00f3n, pone el foco en \u201cla poblaci\u00f3n de ni\u00f1os\/as y adolescentes que en situaci\u00f3n de vulnerabilidad social asisten a escuelas de gesti\u00f3n privada laica o religiosa, cuya escolarizaci\u00f3n supone una contribuci\u00f3n econ\u00f3mica por parte de los hogares\u201d.<\/p>\n\n\n\n<p>El relevamiento de la UCA se suma al informe elaborado por Unicef que se conoci\u00f3 en la jornada de ayer, que revela que 7 de cada 10 ni\u00f1os viven en condiciones de pobreza en la Argentina.<\/p>\n\n\n\n<p>La cifra abarca a cerca de 8,6 millones de menores de 18 a\u00f1os que viven en hogares que no alcanzan el umbral m\u00ednimo de ingresos econ\u00f3micos o en entornos donde se ven privados de sus derechos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un informe de la UCA revela el complejo panorama que atraviesan los j\u00f3venes argentinos que asisten a establecimientos educativos. El impacto de la crisis econ\u00f3mica en la Argentina cada vez se siente m\u00e1s en los ni\u00f1os y adolescentes, lo que se viene reflejando en distintos informes que alertan sobre la creciente poblaci\u00f3n juvenil que cae [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":36768,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[60],"tags":[],"class_list":{"0":"post-74642","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/74642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=74642"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/74642\/revisions"}],"predecessor-version":[{"id":74643,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/74642\/revisions\/74643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/36768"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=74642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=74642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=74642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}