{"id":75486,"date":"2024-04-02T13:38:54","date_gmt":"2024-04-02T16:38:54","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=75486"},"modified":"2024-04-02T13:38:55","modified_gmt":"2024-04-02T16:38:55","slug":"hallaron-el-cuerpo-sin-vida-del-sereno-de-una-obra-en-construccion-en-metan","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2024\/04\/02\/hallaron-el-cuerpo-sin-vida-del-sereno-de-una-obra-en-construccion-en-metan\/","title":{"rendered":"Hallaron el cuerpo sin vida del sereno de una obra en construcci\u00f3n en Metan"},"content":{"rendered":"\n<p>El cuerpo de un hombre sin vida fue hallado este mediod\u00eda en una obra en construcci\u00f3n sobre calle 9 de Julio casi R\u00edo Piedras en la ciudad de Metan.<\/p>\n\n\n\n<p>Las primeras informaciones se\u00f1alan que el hombre oficiaba de sereno en el lugar.<\/p>\n\n\n\n<p>Trabaja personal policial realizando las pericias necesarias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cuerpo de un hombre sin vida fue hallado este mediod\u00eda en una obra en construcci\u00f3n sobre calle 9 de Julio casi R\u00edo Piedras en la ciudad de Metan. Las primeras informaciones se\u00f1alan que el hombre oficiaba de sereno en el lugar. Trabaja personal policial realizando las pericias necesarias.<\/p>\n","protected":false},"author":2,"featured_media":75487,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[63],"tags":[],"class_list":{"0":"post-75486","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policiales"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/75486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=75486"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/75486\/revisions"}],"predecessor-version":[{"id":75488,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/75486\/revisions\/75488"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/75487"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=75486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=75486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=75486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}