{"id":75585,"date":"2024-04-04T10:51:18","date_gmt":"2024-04-04T13:51:18","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=75585"},"modified":"2024-04-04T10:51:19","modified_gmt":"2024-04-04T13:51:19","slug":"paraguay-y-uruguay-registraron-indices-inflacionarios-de-un-digito","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2024\/04\/04\/paraguay-y-uruguay-registraron-indices-inflacionarios-de-un-digito\/","title":{"rendered":"Paraguay y Uruguay registraron \u00edndices inflacionarios de un d\u00edgito"},"content":{"rendered":"\n<p>Los n\u00fameros corresponden a marzo 2024.<\/p>\n\n\n\n<p>La inflaci\u00f3n de marzo en Paraguay, medida por la variaci\u00f3n del \u00cdndice de Precios al Consumidor (IPC), fue del 1,1 por ciento, superior a la variaci\u00f3n del 0,4 por ciento registrada en el mismo mes del a\u00f1o anterior.<\/p>\n\n\n\n<p>Con ello, el \u00edndice acumulado en el primer trimestre en el pa\u00eds sudamericano asciende al 2 por ciento, por debajo del 2,1 por ciento observado en el mismo periodo del 2023, seg\u00fan el informe del Banco Central del Paraguay (BCP) dado a conocer este mi\u00e9rcoles.<\/p>\n\n\n\n<p>Mientras tanto, la inflaci\u00f3n interanual se ubic\u00f3 en un 3,6 por ciento, superior a la tasa del 2,9 por ciento verificada en febrero, pero inferior a la tasa del 6,4 por ciento registrada en el mismo periodo del a\u00f1o pasado.<\/p>\n\n\n\n<p>En Uruguay<\/p>\n\n\n\n<p>La inflaci\u00f3n en Uruguay se redujo al 3,8 por ciento en el a\u00f1o m\u00f3vil con cierre en marzo, desde el 4,71 por ciento en febrero y alcanz\u00f3 el menor nivel desde agosto de 2005 (el 3,4 por ciento), inform\u00f3 el Instituto Nacional de Estad\u00edstica (INE).<\/p>\n\n\n\n<p>De esa manera, el \u00cdndice de Precios del Consumo (IPC) complet\u00f3 10 meses dentro del rango meta (3-6 por ciento) fijado por el Gobierno del presidente Luis Lacalle Pou.<\/p>\n\n\n\n<p>En marzo el IPC tuvo un incremento casi nulo del 0,02 por ciento, por debajo del 0,9 por ciento de marzo de 2023 y en el primer trimestre acumula una suba del 2,20 por ciento, frente al 3,5 por ciento del periodo enero-marzo del a\u00f1o pasado.<\/p>\n\n\n\n<p>Las principales incidencias en el dato de marzo fueron de los rubros alimentos y bebidas no alcoh\u00f3licas, con una baja del 0,56 por ciento e impulsada por ca\u00eddas de la carne y la fruta y un ascenso en promedio de las hortalizas y legumbres.<\/p>\n\n\n\n<p>Le sigui\u00f3 en incidencia Vivienda, Agua y Electricidad, que mostr\u00f3 un incremento del 0,47 por ciento, y Servicios de Educaci\u00f3n, con un alza del 1,99 por ciento.<\/p>\n\n\n\n<p>Uruguay cerr\u00f3 2023 con una inflaci\u00f3n del 5,11 por ciento, el cierre anual m\u00e1s bajo desde el 2005 (+4,9).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los n\u00fameros corresponden a marzo 2024. La inflaci\u00f3n de marzo en Paraguay, medida por la variaci\u00f3n del \u00cdndice de Precios al Consumidor (IPC), fue del 1,1 por ciento, superior a la variaci\u00f3n del 0,4 por ciento registrada en el mismo mes del a\u00f1o anterior. Con ello, el \u00edndice acumulado en el primer trimestre en el [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":75586,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[60],"tags":[],"class_list":{"0":"post-75585","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/75585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=75585"}],"version-history":[{"count":1,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/75585\/revisions"}],"predecessor-version":[{"id":75587,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/75585\/revisions\/75587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/75586"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=75585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=75585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=75585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}