{"id":75591,"date":"2024-04-04T11:12:52","date_gmt":"2024-04-04T14:12:52","guid":{"rendered":"https:\/\/www.todoeldia.com\/?p=75591"},"modified":"2024-04-04T11:40:09","modified_gmt":"2024-04-04T14:40:09","slug":"por-presunto-lavado-en-cordoba-secuestran-siete-autos-una-moto-y-mas-de-30-millones","status":"publish","type":"post","link":"https:\/\/www.todoeldia.com\/index.php\/2024\/04\/04\/por-presunto-lavado-en-cordoba-secuestran-siete-autos-una-moto-y-mas-de-30-millones\/","title":{"rendered":"Por presunto lavado en C\u00f3rdoba secuestran siete autos, una moto y m\u00e1s de $ 30 millones"},"content":{"rendered":"\n<p>Hay un detenido desde 2023. El dinero incautado se compone de d\u00f3lares, pesos y euros. Tambi\u00e9n se encontraron armas de fuego y municiones. En la mira, m\u00e1s de 30 inmuebles.<\/p>\n\n\n\n<p>La Polic\u00eda de Seguridad Aeroportuaria (PSA) incaut\u00f3 autos de lujo, d\u00f3lares y otros bienes costosos en el marco de la causa en la que se investiga a Federico Guillermo M\u00e1scolo (50), quien est\u00e1 detenido e imputado por presunto lavado de activos, luego de cinco allanamientos efectuados en los \u00faltimos d\u00edas en C\u00f3rdoba, informaron fuentes oficiales.<\/p>\n\n\n\n<p>Estos allanamientos se concretaron en Valle Escondido y en la ciudad de Villa Allende, como consecuencia de otros operativos realizados en diciembre de 2023, cuando se detuvo al principal imputado en la causa.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1023\" height=\"575\" src=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/04\/image-22.png\" alt=\"\" class=\"wp-image-75593\" srcset=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/04\/image-22.png 1023w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/04\/image-22-300x169.png 300w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/04\/image-22-768x432.png 768w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/04\/image-22-696x391.png 696w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/04\/image-22-747x420.png 747w\" sizes=\"auto, (max-width: 1023px) 100vw, 1023px\" \/><\/figure>\n\n\n\n<p>Como resultado, se secuestraron siete autos importados de colecci\u00f3n, una moto italiana, U$S 33.451, $ 200 mil, euros, dos armas de fuego, 31 municiones, dispositivos electr\u00f3nicos y documentaci\u00f3n de inter\u00e9s para la causa.<\/p>\n\n\n\n<p>Qui\u00e9n es M\u00e1scolo<\/p>\n\n\n\n<p>El nombre de M\u00e1scolo se asocia desde comienzos de la d\u00e9cada pasada con varios nombres de la pol\u00edtica y de la obra p\u00fablica provincial y de municipios cordobeses<\/p>\n\n\n\n<p>En noviembre \u00faltimo, el fiscal federal N\u00b0 3 de C\u00f3rdoba, Maximiliano Hairabedian, lo hab\u00eda imputado por supuesto lavado; y un mes despu\u00e9s, M\u00e1scolo qued\u00f3 detenido.<\/p>\n\n\n\n<p>Se se\u00f1ala que adquiri\u00f3 numerosos inmuebles y veh\u00edculos por medio de un \u201cprestanombre\u201d. Dada la inactividad de las empresas constructoras que otrora facturaron cifras millonarias a la administraci\u00f3n p\u00fablica y la falta de ingresos justificables, se le formula la imputaci\u00f3n con la presunci\u00f3n de fondo de que existe evasi\u00f3n impositiva.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1023\" height=\"621\" src=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/04\/image-23.png\" alt=\"\" class=\"wp-image-75594\" srcset=\"https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/04\/image-23.png 1023w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/04\/image-23-300x182.png 300w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/04\/image-23-768x466.png 768w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/04\/image-23-696x422.png 696w, https:\/\/www.todoeldia.com\/wp-content\/uploads\/2024\/04\/image-23-692x420.png 692w\" sizes=\"auto, (max-width: 1023px) 100vw, 1023px\" \/><\/figure>\n\n\n\n<p>V\u00ednculos visibles<\/p>\n\n\n\n<p>M\u00e1scolo ha estado ligado a la obra p\u00fablica desde comienzos de la d\u00e9cada pasada, a trav\u00e9s de varias empresas constructoras, como MB Constructora (con su esposa), M\u00e1scolo Constructora, MH SRL y MH Empresa de Servicios, entre otras.<\/p>\n\n\n\n<p>En febrero de 2017, M\u00e1scolo tambi\u00e9n lleg\u00f3 a las noticias porque durante algunas horas un grupo de delincuentes protagoniz\u00f3 un secuestro extorsivo con un familiar como v\u00edctima, y hubo pago de recompensa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hay un detenido desde 2023. El dinero incautado se compone de d\u00f3lares, pesos y euros. Tambi\u00e9n se encontraron armas de fuego y municiones. En la mira, m\u00e1s de 30 inmuebles. La Polic\u00eda de Seguridad Aeroportuaria (PSA) incaut\u00f3 autos de lujo, d\u00f3lares y otros bienes costosos en el marco de la causa en la que se [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":75592,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[63],"tags":[],"class_list":{"0":"post-75591","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policiales"},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/75591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=75591"}],"version-history":[{"count":2,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/75591\/revisions"}],"predecessor-version":[{"id":75597,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/posts\/75591\/revisions\/75597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media\/75592"}],"wp:attachment":[{"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=75591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=75591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoeldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=75591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}